{"id":569,"date":"2013-03-21T00:00:00","date_gmt":"2013-03-21T03:00:00","guid":{"rendered":"https:\/\/clam.org.br\/en\/2013\/03\/21\/the-best-childbirth-labor-is-normal-and-physiologic\/"},"modified":"2013-03-21T00:00:00","modified_gmt":"2013-03-21T03:00:00","slug":"the-best-childbirth-labor-is-normal-and-physiologic","status":"publish","type":"post","link":"https:\/\/clam.org.br\/en\/interviews\/the-best-childbirth-labor-is-normal-and-physiologic\/569\/","title":{"rendered":"THE BEST CHILDBIRTH LABOR IS NORMAL AND PHYSIOLOGIC"},"content":{"rendered":"<p>A conclus&atilde;o do Comit&ecirc; das Na&ccedil;&otilde;es Unidas pelo Fim de Toda Discrimina&ccedil;&atilde;o Contra Mulheres (CEDAW) de que o Brasil violou o direito &agrave; sa&uacute;de no caso de Alyne da Silva Pimentel &ndash; a jovem de 27 anos v&iacute;tima de morte materna decorrente de uma s&eacute;rie de falhas no atendimento obst&eacute;trico &ndash; e a recomenda&ccedil;&atilde;o para que o Estado brasileiro implemente medidas efetivas para redu&ccedil;&atilde;o da mortalidade materna, lan&ccedil;ou luz sobre a necessidade de melhoria do acesso &agrave; qualidade de aten&ccedil;&atilde;o pr&eacute;-natal e obst&eacute;trica no pa&iacute;s.<\/p>\n<p>Passados quase dois anos da decis&atilde;o do CEDAW, ainda n&atilde;o h&aacute; respostas concretas do governo brasileiro, e o que se v&ecirc; ainda s&atilde;o viol&ecirc;ncias no parto, uso de t&eacute;cnicas invasivas e altas taxas de interven&ccedil;&otilde;es sem consentimento que p&otilde;em em risco a integridade corporal, a dignidade e o bem-estar emocional da mulher, al&eacute;m de um sistema com &ecirc;nfase na produtividade e lucratividade que explora a ideia do parto como algo doloroso e terr&iacute;vel e coloca o pa&iacute;s na posi&ccedil;&atilde;o de campe&atilde;o mundial no n&uacute;mero de cesarianas.<\/p>\n<p>Nesta entrevista, feita em fun&ccedil;&atilde;o do Dia Internacional da Mulher (8 de mar&ccedil;o), a m&eacute;dica Simone Grilo Diniz, professora do Departamento de Sa&uacute;de Materno-infantil da Faculdade de Sa&uacute;de P&uacute;blica da USP, discute as problematiza&ccedil;&otilde;es nas pol&iacute;ticas p&uacute;blicas de sa&uacute;de materno-infantil no Brasil &agrave; luz do conceito de &lsquo;humaniza&ccedil;&atilde;o&rsquo;, interpreta os altos &iacute;ndices de cesarianas e gravidezes n&atilde;o planejadas e analisa a Rede Cegonha, programa lan&ccedil;ado em 2011 para ser o carro-chefe do governo para a sa&uacute;de das mulheres.<\/p>\n<p><b>A falta de humaniza&ccedil;&atilde;o ainda caracteriza o modelo de assist&ecirc;ncia materno-infantil no pa&iacute;s?<\/b><\/p>\n<p>Quando falamos em &lsquo;humaniza&ccedil;&atilde;o&rsquo; estamos tratando de uma mudan&ccedil;a nas rela&ccedil;&otilde;es e mudan&ccedil;a de pr&aacute;ticas de assist&ecirc;ncia e das interven&ccedil;&otilde;es. Trata-se de uma aten&ccedil;&atilde;o que tenta preservar a integridade&nbsp;genital da mulher, onde ela tem liberdade de posi&ccedil;&atilde;o no parto, e onde ela n&atilde;o &eacute; submetida a medicamentos sem ser informada ou sem consentir. A humaniza&ccedil;&atilde;o se refere a como a assist&ecirc;ncia &eacute; organizada, ao direito ao acompanhante, &agrave; manuten&ccedil;&atilde;o da integridade corporal da mulher, ao uso de procedimentos consentidos e &agrave; garantia de autonomia. Esse &eacute; o modelo de que fala o movimento pela humaniza&ccedil;&atilde;o do parto.<\/p>\n<p>No entanto, o que se observa ainda s&atilde;o altas taxas de interven&ccedil;&atilde;o &ndash; como a episiotomia &ndash;, as mulheres continuando a dar &agrave; luz na posi&ccedil;&atilde;o litot&ocirc;mica &ndash; chamada inforrmalmente de &lsquo;frango assado&rsquo; &ndash; e outras pr&aacute;ticas que se distanciam do modelo de humaniza&ccedil;&atilde;o. Todas essas formas de assist&ecirc;ncia n&atilde;o promovem a dignidade nem o bem estar emocional das mulheres. Nesse sentindo, eu diria que a falta de humaniza&ccedil;&atilde;o ainda caracteriza o modelo de assist&ecirc;ncia materno-infantil no pa&iacute;s. Esse parto agressivo faz com a cesariana termine parecendo, comparativamente, muito mais aceit&aacute;vel.<\/p>\n<p><b>O alto &iacute;ndice de cesarianas no pa&iacute;s &eacute; alarmante: o &iacute;ndice de 82% de partos cir&uacute;rgicos na rede privada brasileira &eacute; o mais alto do mundo. Como interpreta este dado e quais as implica&ccedil;&otilde;es deste alto &iacute;ndice de cesarianas?<\/b><\/p>\n<p>No Brasil h&aacute; uma ideia do parto como algo indigno, nojento, uma maldi&ccedil;&atilde;o pela qual a mulher tem que passar pelo fato de ter tido vida sexual. Da&iacute; se segue o que chamamos de uma &ldquo;abordagem correcional do parto&rdquo; &ndash; como o uso de ocitocina, por exemplo, para tornar mais intensas as contra&ccedil;&otilde;es uterinas, at&eacute; que o&nbsp;beb&ecirc; nas&ccedil;a.<\/p>\n<p>Nessa perspectiva, o parto terr&iacute;vel deve ser prevenido atrav&eacute;s da cesariana. Assim, ela &eacute; uma pr&aacute;tica usada como recurso no Brasil para se livrar de uma experi&ecirc;ncia de parto indigna e violenta. Em outros pa&iacute;ses, mesmo nos muito medicalizados como os EUA, a maioria das cesarianas ocorre em&nbsp;mulheres pobres e doentes. Aqui a maioria ocorre nas saud&aacute;veis e mais ricas, porque parece algo menos terr&iacute;vel. Os servi&ccedil;os de sa&uacute;de s&atilde;o organizados com base nessa cren&ccedil;a. Se n&atilde;o mudarmos a cultura sexual-reprodutivo que est&aacute; inscrita nos modelo de assist&ecirc;ncia e na&nbsp;ambi&ecirc;ncia dos servi&ccedil;os de sa&uacute;de, isso n&atilde;o vai melhorar.<\/p>\n<p>Enquanto o resto do mundo acredita que o&nbsp;tipo de parto mais vantajoso para as mulheres terem beb&ecirc;s saud&aacute;veis &eacute; o normal e fisiol&oacute;gico, no Brasil os conflitos de interesse pesam muito. O que chama a aten&ccedil;&atilde;o, no caso brasileiro, &eacute; que em rela&ccedil;&atilde;o a outros tipos de assist&ecirc;ncia &ndash; como a que envolve os antirretrovirais, por exemplo &ndash; h&aacute; um padr&atilde;o ouro. No parto n&atilde;o. As mulheres n&atilde;o pagantes&nbsp;n&atilde;o t&ecirc;m direito a decidir nada. H&aacute; um conjunto de contradi&ccedil;&otilde;es culturais.<\/p>\n<p><b>A Rede Cegonha foi lan&ccedil;ada para ser o carro-chefe do governo para a sa&uacute;de das mulheres. Como avalia o programa? Acha que ele d&aacute; conta de aten&ccedil;&atilde;o ao parto ou &eacute; uma solu&ccedil;&atilde;o fal&iacute;vel?<\/b><\/p>\n<p>O nome&nbsp;Rede Cegonha sinaliza uma ruptura na alian&ccedil;a hist&oacute;rica da &aacute;rea t&eacute;cnica da sa&uacute;de da mulher com o movimento de mulheres, uma vez que ela despolitiza e dessexualiza o debate sobre reprodu&ccedil;&atilde;o. A pr&oacute;pria ideia de cegonha fica aqu&eacute;m do humano. A escolha do nome sinaliza um alinhamento com os setores religiosos, do qual o governo tem se mostrado ref&eacute;m. O programa aponta para uma retomada do foco do materno-infantilismo, centra muito a aten&ccedil;&atilde;o na mulher-m&atilde;e. A &aacute;rea t&eacute;cnica est&aacute; ocupada por pessoas que entendem sobre humaniza&ccedil;&atilde;o do parto, e que at&eacute; tentam ampliar a agenda, mas que t&ecirc;m sido impedidas de tomar atitudes por conta das alian&ccedil;as com os setores religiosos, que fazem parte do governo Dilma.<\/p>\n<p>O programa ent&atilde;o tenta lidar com temas mais aceit&aacute;veis, como a contracep&ccedil;&atilde;o, mas isso nem de longe lembra a agenda ampla do PAISM [Programa de Assist&ecirc;ncia Integral &agrave; Sa&uacute;de da Mulher], muito voltado para a ideia de informa&ccedil;&atilde;o em sa&uacute;de, o que praticamente desapareceu da agenda do SUS. Existe uma redu&ccedil;&atilde;o da ideia de integralidade e uma fragmenta&ccedil;&atilde;o da assist&ecirc;ncia. A qualidade da informa&ccedil;&atilde;o &eacute; preocupante. Esta &eacute; uma &aacute;rea que precisa melhorar muito.<\/p>\n<p>N&atilde;o diria, por&eacute;m, que seja um programa fal&iacute;vel. Ele tem aspectos positivos na ideia de aten&ccedil;&atilde;o ao parto. A Rede Cegonha por um lado tem um discurso inovador em termos de promover um modelo respeitoso e fisiol&oacute;gico, mas por outro cai num sistema altamente medicalizado. O modelo m&eacute;dico-centrado &eacute; um dos problemas principais. O que precisamos &eacute; de um profissional especialista em parto normal. Mas a ideia de produtividade e lucratividade &eacute; o que emperra o sistema.<\/p>\n<p><b>O Brasil conseguiu diminuir a mortalidade infantil, mas a redu&ccedil;&atilde;o da mortalidade materna ainda &eacute; um desafio que persiste, n&atilde;o &eacute;?<\/b><\/p>\n<p>Sa&uacute;de materna tem sido reduzida &agrave; quest&atilde;o da mortalidade materna. Esquece-se de olhar para outras quest&otilde;es importantes, como a morbidade e os danos perineais resultantes de um modelo de assist&ecirc;ncia agressivo, assim como as complica&ccedil;&otilde;es de cesarea nas mulheres. No Brasil n&atilde;o temos sequer informa&ccedil;&atilde;o sobre o uso da episiotomia no Data SUS. Damos tamb&eacute;m muito pouca aten&ccedil;&atilde;o ao estresse e &agrave; depress&atilde;o p&oacute;s-parto, causas de suic&iacute;dio entre mulheres.<\/p>\n<p>H&aacute; ainda a quest&atilde;o da viol&ecirc;ncia no parto, problemas de sa&uacute;de mental, as interven&ccedil;&otilde;es e o uso de drogas como a ocitocina sint&eacute;tica. No Brasil usamos essa droga para acelerar os partos sem qualquer regula&ccedil;&atilde;o. S&atilde;o quest&otilde;es associadas &agrave; mortalidade. H&aacute; tamb&eacute;m as mortes por falta de uso de tecnologia e pelo uso indiscriminado de tecnologias. O problema &eacute; que n&atilde;o existe regula&ccedil;&atilde;o da qualidade da assist&ecirc;ncia no Brasil.<\/p>\n<p>Fazer uma episiotomia ou usar a ocitocina sem consentimento &eacute; uma viol&ecirc;ncia contra a mulher. Mas o sofrimento gerado pelas agress&otilde;es no parto s&atilde;o sempre atribu&iacute;das ao parto vaginal, n&atilde;o ao tratamento agressivo, refor&ccedil;ando a cren&ccedil;a do parto como castigo.<\/p>\n<p>Por isso, por aqui a pr&aacute;tica da cesariana &eacute; vendida como o parto ideal, como sendo o padr&atilde;o ouro da assist&ecirc;ncia, e se as mulheres pagarem por isso v&atilde;o ter uma melhor experi&ecirc;ncia no parto. Isso acontece porque n&atilde;o existe regula&ccedil;&atilde;o. Mesmo em pa&iacute;ses muito medicalizados como os EUA h&aacute; uma recomenda&ccedil;&atilde;o forte de n&atilde;o se fazer cesariana quando a gravidez tiver menos de 39 semanas completas. A maioria das cesarianas feitas no setor privado no Brasil acontece antes disso. Os americanos regulam porque h&aacute; muitos danos associados &agrave; pr&aacute;tica.<\/p>\n<p><b>Que danos seriam estes?<\/b><\/p>\n<p>Danos para as mulheres, mas principalmente os relacionados &agrave; maneira como a pessoa nasce. Quem nasce atrav&eacute;s de cesariana tem mais chances de desenvolver obesidade, asma, diabetes tipo 1 e 2. Isto pode acontecer porque, quando a crian&ccedil;a est&aacute; no &uacute;tero materno &eacute; est&eacute;ril, isto &eacute;, livre de qualquer contamina&ccedil;&atilde;o. Nos partos vaginais, as primeiras bact&eacute;rias que tomam conta de seu intestino s&atilde;o altamente ben&eacute;ficas. Quem nasce por cesariana vai ser colonizado por bact&eacute;rias hospitalares de quem o manipula. E o tipo de bact&eacute;ria que voc&ecirc; adquire neste momento vai influir em como voc&ecirc; absorve vitamina,&nbsp;calorias, enfim, como seu organismo se configure em termos metab&oacute;licos e imunol&oacute;gicos&nbsp;.<\/p>\n<p><b>No contexto latino-americano o Brasil &eacute; o &uacute;nico a ter esses problemas na assist&ecirc;ncia &agrave; sa&uacute;de materno-infantil?<\/b><\/p>\n<p>Brasil e Chile s&atilde;o exemplos extremos de medicaliza&ccedil;&atilde;o excessiva. J&aacute; os venezuelanos t&ecirc;m leis de combate &agrave; viol&ecirc;ncia obst&eacute;trica. A Venezuela, quando lan&ccedil;ou o equivalente a nossa lei Maria da Penha, j&aacute; incluiu a quest&atilde;o da viol&ecirc;ncia obst&eacute;trica. L&aacute;, os abusos verbais e o cuidado n&atilde;o consentido s&atilde;o considerados formas de viol&ecirc;ncia.<\/p>\n<p><b>Resultados do estudo &ldquo;Nascer no Brasil: Inqu&eacute;rito sobre parto e nascimento&rdquo;, divulgado pela Ensp\/Fiocruz no ano passado, revelam que apenas 45% das mulheres planejaram a gravidez. A que se deve isto? H&aacute; problemas no acesso a esse planejamento?<\/b><\/p>\n<p>Temos alta taxa de&nbsp;contracep&ccedil;&atilde;o,&nbsp;mas basicamente esteriliza&ccedil;&atilde;o, m&eacute;todos&nbsp;hormonais, a camisinha e uma alta taxa de gravidez n&atilde;o desejada. O que isso reflete? Reflete que vivemos em um pa&iacute;s onde as a&ccedil;&otilde;es educativas desapareceram e o aborto continua sendo ilegal. H&aacute; pouca informa&ccedil;&atilde;o sobre como prevenir uma gravidez e um leque restrito de op&ccedil;&otilde;es contraceptivas.<\/p>\n<p>A PNDS de 2006 (referente ao per&iacute;odo 2001- 2005) apontava um uso zero de diafragma. H&aacute; diafragmas nos postos, mas n&atilde;o tem quem prescreva ou quem oriente. N&atilde;o h&aacute; quem saiba orientar.<\/p>\n<p>Ao mesmo tempo, os anticoncepcionais hormonais causam muitos efeitos adversos, o que faz com que muitas mulheres abandonem o m&eacute;todo e busquem outros. Mas tem que haver outras op&ccedil;&otilde;es. O Diu &eacute; um m&eacute;todo bom para ser usado entre uma gravidez e outra, por exemplo. Nosso leque de m&eacute;todos contraceptivos &eacute; muito restrito.<\/p>\n<p>Al&eacute;m disso, existe uma inequidade no acesso ao aborto no pa&iacute;s, mesmo nos casos previstos em lei a m&aacute; qualidade de assist&ecirc;ncia &eacute; extrema. A tecnologia utilizada em abortos incompletos &eacute; obsoleta, dolorosa e insegura.<\/p>\n<p><b>Considerando a realiza&ccedil;&atilde;o pr&oacute;xima do Semin&aacute;rio de Avalia&ccedil;&atilde;o do PNAISM, marcado para o segundo semestre de 2013, o que pode ser sugerido em termos de melhorias para o sistema de atendimento na &aacute;rea da sa&uacute;de da mulher?<\/b><\/p>\n<p>A iniciativa do semin&aacute;rio &eacute; muito importante. A integralidade em sa&uacute;de precisa ser retomada neste momento de revisita ao PNAISM. Estamos vivendo uma outra realidade hoje. Temos as velhas quest&otilde;es n&atilde;o resolvidas e as novas. Precisamos nos atualizar para enfrent&aacute;-las.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In this special interview on International Women&#8221;s Day, Simone Diniz, physician at the Maternal and Infant Health Department of University of S\u00e3o Paulo School of Public Health, makes an assessment of public policy on maternal and child health through the lens of \u2018humanizing care&#8221; and discusses the high incidence of c-sections and unplanned pregnancies in Brasil.<i>(Text in Portuguese)<\/i><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[8],"tags":[],"class_list":["post-569","post","type-post","status-publish","format-standard","hentry","category-interviews"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>THE BEST CHILDBIRTH LABOR IS NORMAL AND PHYSIOLOGIC - CLAM - EN<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clam.org.br\/en\/interviews\/the-best-childbirth-labor-is-normal-and-physiologic\/569\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"THE BEST CHILDBIRTH LABOR IS NORMAL AND PHYSIOLOGIC - CLAM - EN\" \/>\n<meta property=\"og:description\" content=\"In this special interview on International Women&quot;s Day, Simone Diniz, physician at the Maternal and Infant Health Department of University of S\u00e3o Paulo School of Public Health, makes an assessment of public policy on maternal and child health through the lens of \u2018humanizing care&quot; and discusses the high incidence of c-sections and unplanned pregnancies in Brasil.(Text in Portuguese)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clam.org.br\/en\/interviews\/the-best-childbirth-labor-is-normal-and-physiologic\/569\/\" \/>\n<meta property=\"og:site_name\" content=\"CLAM - EN\" \/>\n<meta property=\"article:published_time\" content=\"2013-03-21T03:00:00+00:00\" \/>\n<meta name=\"author\" content=\"fw2\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"fw2\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/en\\\/interviews\\\/the-best-childbirth-labor-is-normal-and-physiologic\\\/569\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/en\\\/interviews\\\/the-best-childbirth-labor-is-normal-and-physiologic\\\/569\\\/\"},\"author\":{\"name\":\"fw2\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/en\\\/#\\\/schema\\\/person\\\/fbd9a86032bf7479f94b0ded196f1010\"},\"headline\":\"THE BEST CHILDBIRTH LABOR IS NORMAL AND PHYSIOLOGIC\",\"datePublished\":\"2013-03-21T03:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/en\\\/interviews\\\/the-best-childbirth-labor-is-normal-and-physiologic\\\/569\\\/\"},\"wordCount\":2392,\"articleSection\":[\"Interviews\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/en\\\/interviews\\\/the-best-childbirth-labor-is-normal-and-physiologic\\\/569\\\/\",\"url\":\"https:\\\/\\\/clam.org.br\\\/en\\\/interviews\\\/the-best-childbirth-labor-is-normal-and-physiologic\\\/569\\\/\",\"name\":\"THE BEST CHILDBIRTH LABOR IS NORMAL AND PHYSIOLOGIC - CLAM - EN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/en\\\/#website\"},\"datePublished\":\"2013-03-21T03:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/en\\\/#\\\/schema\\\/person\\\/fbd9a86032bf7479f94b0ded196f1010\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/en\\\/interviews\\\/the-best-childbirth-labor-is-normal-and-physiologic\\\/569\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/clam.org.br\\\/en\\\/interviews\\\/the-best-childbirth-labor-is-normal-and-physiologic\\\/569\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/en\\\/interviews\\\/the-best-childbirth-labor-is-normal-and-physiologic\\\/569\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/clam.org.br\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"THE BEST CHILDBIRTH LABOR IS NORMAL AND PHYSIOLOGIC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/clam.org.br\\\/en\\\/\",\"name\":\"CLAM - EN\",\"description\":\"S\u00f3 mais um site CLAM - Centro Latino-Americano em Sexualidade e Direitos Humanos sites\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/clam.org.br\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/en\\\/#\\\/schema\\\/person\\\/fbd9a86032bf7479f94b0ded196f1010\",\"name\":\"fw2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g\",\"caption\":\"fw2\"},\"sameAs\":[\"https:\\\/\\\/clam.org.br\"],\"url\":\"https:\\\/\\\/clam.org.br\\\/en\\\/author\\\/fw2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"THE BEST CHILDBIRTH LABOR IS NORMAL AND PHYSIOLOGIC - CLAM - EN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clam.org.br\/en\/interviews\/the-best-childbirth-labor-is-normal-and-physiologic\/569\/","og_locale":"en_US","og_type":"article","og_title":"THE BEST CHILDBIRTH LABOR IS NORMAL AND PHYSIOLOGIC - CLAM - EN","og_description":"In this special interview on International Women\"s Day, Simone Diniz, physician at the Maternal and Infant Health Department of University of S\u00e3o Paulo School of Public Health, makes an assessment of public policy on maternal and child health through the lens of \u2018humanizing care\" and discusses the high incidence of c-sections and unplanned pregnancies in Brasil.(Text in Portuguese)","og_url":"https:\/\/clam.org.br\/en\/interviews\/the-best-childbirth-labor-is-normal-and-physiologic\/569\/","og_site_name":"CLAM - EN","article_published_time":"2013-03-21T03:00:00+00:00","author":"fw2","twitter_card":"summary_large_image","twitter_misc":{"Written by":"fw2","Est. reading time":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/clam.org.br\/en\/interviews\/the-best-childbirth-labor-is-normal-and-physiologic\/569\/#article","isPartOf":{"@id":"https:\/\/clam.org.br\/en\/interviews\/the-best-childbirth-labor-is-normal-and-physiologic\/569\/"},"author":{"name":"fw2","@id":"https:\/\/clam.org.br\/en\/#\/schema\/person\/fbd9a86032bf7479f94b0ded196f1010"},"headline":"THE BEST CHILDBIRTH LABOR IS NORMAL AND PHYSIOLOGIC","datePublished":"2013-03-21T03:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/clam.org.br\/en\/interviews\/the-best-childbirth-labor-is-normal-and-physiologic\/569\/"},"wordCount":2392,"articleSection":["Interviews"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/clam.org.br\/en\/interviews\/the-best-childbirth-labor-is-normal-and-physiologic\/569\/","url":"https:\/\/clam.org.br\/en\/interviews\/the-best-childbirth-labor-is-normal-and-physiologic\/569\/","name":"THE BEST CHILDBIRTH LABOR IS NORMAL AND PHYSIOLOGIC - CLAM - EN","isPartOf":{"@id":"https:\/\/clam.org.br\/en\/#website"},"datePublished":"2013-03-21T03:00:00+00:00","author":{"@id":"https:\/\/clam.org.br\/en\/#\/schema\/person\/fbd9a86032bf7479f94b0ded196f1010"},"breadcrumb":{"@id":"https:\/\/clam.org.br\/en\/interviews\/the-best-childbirth-labor-is-normal-and-physiologic\/569\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/clam.org.br\/en\/interviews\/the-best-childbirth-labor-is-normal-and-physiologic\/569\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/clam.org.br\/en\/interviews\/the-best-childbirth-labor-is-normal-and-physiologic\/569\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/clam.org.br\/en\/"},{"@type":"ListItem","position":2,"name":"THE BEST CHILDBIRTH LABOR IS NORMAL AND PHYSIOLOGIC"}]},{"@type":"WebSite","@id":"https:\/\/clam.org.br\/en\/#website","url":"https:\/\/clam.org.br\/en\/","name":"CLAM - EN","description":"S\u00f3 mais um site CLAM - Centro Latino-Americano em Sexualidade e Direitos Humanos sites","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clam.org.br\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/clam.org.br\/en\/#\/schema\/person\/fbd9a86032bf7479f94b0ded196f1010","name":"fw2","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g","caption":"fw2"},"sameAs":["https:\/\/clam.org.br"],"url":"https:\/\/clam.org.br\/en\/author\/fw2\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":false,"_links":{"self":[{"href":"https:\/\/clam.org.br\/en\/wp-json\/wp\/v2\/posts\/569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clam.org.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clam.org.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clam.org.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/clam.org.br\/en\/wp-json\/wp\/v2\/comments?post=569"}],"version-history":[{"count":0,"href":"https:\/\/clam.org.br\/en\/wp-json\/wp\/v2\/posts\/569\/revisions"}],"wp:attachment":[{"href":"https:\/\/clam.org.br\/en\/wp-json\/wp\/v2\/media?parent=569"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clam.org.br\/en\/wp-json\/wp\/v2\/categories?post=569"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clam.org.br\/en\/wp-json\/wp\/v2\/tags?post=569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}