{"id":1015,"date":"2015-01-14T00:00:00","date_gmt":"2015-01-14T02:00:00","guid":{"rendered":"https:\/\/clam.org.br\/es\/2015\/01\/14\/numeros-del-matrimonio\/"},"modified":"2015-01-14T00:00:00","modified_gmt":"2015-01-14T02:00:00","slug":"numeros-del-matrimonio","status":"publish","type":"post","link":"https:\/\/clam.org.br\/es\/noticias-clam\/numeros-del-matrimonio\/1015\/","title":{"rendered":"N\u00fameros del matrimonio"},"content":{"rendered":"<p>Pela primeira vez na hist&oacute;ria, o Brasil mapeou oficialmente o n&uacute;mero  de casamentos civis entre pessoas do mesmo sexo. A pesquisa <i><a href=\"http:\/\/www.ibge.gov.br\/home\/estatistica\/populacao\/registrocivil\/2013\/default_pdf.shtm\" target=\"_blank\" rel=\"noopener\">Estat&iacute;sticas do Registro Civil<\/a><\/i>, realizada pelo IBGE, mostrou 3.701 casamentos homoafetivos oficializados em 2013.<\/p>\n<p>De acordo com o estudo, tais casamentos homoafetivos representaram  0,35% do total de uni&otilde;es do tipo celebradas no pa&iacute;s em 2013 (1.048.776).  Na divis&atilde;o por g&ecirc;nero, os casais compostos por mulheres foram  respons&aacute;veis por 1956 casamentos (52%) e os compostos por homens  representaram 1775 (48%). A diferen&ccedil;a n&atilde;o &eacute; t&atilde;o significativa se  considerarmos o fato de as mulheres serem maioria na popula&ccedil;&atilde;o &ndash; existem  5,2 milh&otilde;es a mais, de acordo com a Pesquisa Nacional por Amostra de  Domic&iacute;lio (PNAD) de 2013. Esse relativo equil&iacute;brio entre casamentos  entre homens e entre mulheres parece contradizer o senso comum de que  l&eacute;sbicas tenderiam a se casar mais do que gays.<\/p>\n<p>Entretanto, outros dados apontam para diferen&ccedil;as importantes. A  regi&atilde;o Sudeste, por exemplo, concentrou a maioria dos casamentos  homoafetivos: 2408 foram realizados na regi&atilde;o, ao passo que as outras  regi&otilde;es registraram n&uacute;meros significativamente menores: Sul (525);  Nordeste (497); Centro-Oeste (215); Norte (56). Na pondera&ccedil;&atilde;o por 100  mil habitantes, o Sudeste tamb&eacute;m lidera o ranking, com 3 casamentos  entre pessoas do mesmo sexo para cada 100 mil. O Sul ficou em segundo,  com 2\/100 mil; Centro-Oeste, com 1,5\/100 mil; Nordeste, com 1\/100 mil e  Norte, com 0,35\/100 mil.<\/p>\n<p>O contexto regional parece ser, portanto, um elemento importante a se  considerar. E n&atilde;o apenas devido &agrave;s desigualdades socioecon&ocirc;micas &ndash; o  Sudeste &eacute; a regi&atilde;o mais populosa (80.353.724), industrializada e com  maior participa&ccedil;&atilde;o no Produto Interno Bruto (PIB). Uma das hip&oacute;teses  levantadas pelo professor Sergio Carrara (CLAM\/IMS\/UERJ) &eacute; que, no Rio  de Janeiro e em S&atilde;o Paulo, tem havido iniciativas do poder p&uacute;blico no  sentido de promover a cidadania LGBT. Tanto que em ambos os estados  cerim&ocirc;nias de casamentos coletivos s&atilde;o organizadas periodicamente para  celebrar a uni&atilde;o de pessoas do mesmo sexo. Em dezembro de 2013, a  Superintend&ecirc;ncia de Direitos Individuais, Coletivos e Difusos  (SuperDIR), do Rio de Janeiro, <a href=\"http:\/\/www.rj.gov.br\/web\/seasdh\/exibeconteudo?article-id=1884759\" target=\"_blank\" rel=\"noopener\">promoveu cerim&ocirc;nia coletiva para 130 casais homoafetivos<\/a>,  colocando o m&ecirc;s como o per&iacute;odo com maior n&uacute;mero de uni&otilde;es entre  mulheres no estado e na capital. Em S&atilde;o Paulo, o poder p&uacute;blico, atrav&eacute;s  da Secretaria Estadual da Justi&ccedil;a e da Defesa da Cidadania e a  Coordenadoria Municipal de Assuntos da Diversidade Sexual, constituem  ferramentas de promo&ccedil;&atilde;o de direitos LGBT. O estado de S&atilde;o Paulo, por  exemplo, foi respons&aacute;vel por 1945 celebra&ccedil;&otilde;es em 2013, totalizando mais  de 50% do total de casamentos homoafetivos realizados no pa&iacute;s.<\/p>\n<p>Esta &eacute; uma mirada parcial sobre as a&ccedil;&otilde;es dos Poderes Executivos pelo  Pa&iacute;s. Desde 2011, vale dizer, avan&ccedil;os t&ecirc;m sido obtidos no &acirc;mbito dos  direitos civis de pessoas LGBT tamb&eacute;m em outras esferas. Naquele ano, o  Supremo Tribunal Federal reconheceu a uni&atilde;o civil entre pessoas do mesmo  sexo, equiparando-a &agrave;s uni&otilde;es heterossexuais e garantindo, portanto,  uma s&eacute;rie de direitos at&eacute; ent&atilde;o inexistentes. Em 2013, o Conselho  Nacional de Justi&ccedil;a (CNJ) aprovou resolu&ccedil;&atilde;o obrigando os cart&oacute;rios a  converter em casamento civil as uni&otilde;es est&aacute;veis homoafetivas. J&aacute; no  Congresso, o cen&aacute;rio &eacute; menos animador, em raz&atilde;o da atua&ccedil;&atilde;o de setores  religiosos dogm&aacute;ticos que impedem a amplia&ccedil;&atilde;o de direitos LGBT.<\/p>\n<p>Para Sergio Carrara, a pesquisa do IBGE levanta muitas outras  reflex&otilde;es.  &ldquo;O Sudeste &eacute; uma regi&atilde;o com forte urbaniza&ccedil;&atilde;o, o que tende a  favorecer a individualiza&ccedil;&atilde;o e a enfraquecer a press&atilde;o de fam&iacute;lias e  comunidades no sentido de que tais uni&otilde;es n&atilde;o sejam publicamente  (re)conhecidas. H&aacute; que refletir tamb&eacute;m sobre a import&acirc;ncia da classe  social nessa distribui&ccedil;&atilde;o diferencial de casamentos. Ainda n&atilde;o &eacute;  poss&iacute;vel ter conclus&otilde;es a partir da pesquisa, sobretudo porque o pa&iacute;s &eacute;  muito diverso e porque muitos fatores condicionam esses n&uacute;meros.  Urbaniza&ccedil;&atilde;o, condi&ccedil;&otilde;es socioecon&ocirc;micas, classe social, estrutura e a&ccedil;&atilde;o  do Estado, o custo do casamento &ndash; que varia por estado -, entre outros  fatores, s&atilde;o interessantes para a avalia&ccedil;&atilde;o dos dados da pesquisa&rdquo;,  pondera Sergio Carrara.<\/p>\n<p>De fato, o Sudeste concentra o maior n&uacute;mero absoluto de casamentos  entre pessoas do mesmo sexo e tamb&eacute;m o maior o n&uacute;mero na pondera&ccedil;&atilde;o por  100 mil habitantes. Mas, quando se compara os dados a partir da  pondera&ccedil;&atilde;o do n&uacute;mero total de casamentos (heterossexuais e homossexuais)  por 100 mil, o Centro-Oeste desponta como primeiro lugar. Em 2013, o  n&uacute;mero total de casamentos na regi&atilde;o foi de 635 para cada 100 mil  habitantes. O Sudeste fica em segundo lugar, com 633\/100 mil. &ldquo;S&atilde;o  n&uacute;meros que abrem muitas perguntas. Por que, considerando-se os  casamentos heterossexuais, casa-se mais no Centro-Oeste? Que fatores  levam as pessoas a buscar a oficializa&ccedil;&atilde;o do casamento? Como isso se  relaciona com as rela&ccedil;&otilde;es sociais locais? Por ser a primeira vez que  esse tipo de mensura&ccedil;&atilde;o &eacute; feita, ainda &eacute; cedo para conclus&otilde;es. Ainda n&atilde;o  &eacute; poss&iacute;vel tra&ccedil;ar uma linha de tend&ecirc;ncias. Em todo caso, a pesquisa  servir&aacute; como marco zero para a medi&ccedil;&atilde;o das tend&ecirc;ncias e para a an&aacute;lise  social no campo da cidadania LGBT&rdquo;, finaliza Sergio Carrara.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Primer mapeo de uniones entre personas del mismo sexo en Brasil muestra que hubo 3.701 en 2013. Para el profesor Sergio Carrara (CLAM\/IMS\/UERJ), si bien es peque\u00f1o comparado con las uniones heterosexuales, el n\u00famero muestra la importancia de las pol\u00edticas de promoci\u00f3n de la ciudadan\u00eda LGBT. <i>(Texto en portugu\u00e9s)<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-1015","post","type-post","status-publish","format-standard","hentry","category-noticias-clam"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>N\u00fameros del matrimonio - CLAM - ES<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clam.org.br\/es\/noticias-clam\/numeros-del-matrimonio\/1015\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"N\u00fameros del matrimonio - CLAM - ES\" \/>\n<meta property=\"og:description\" content=\"Primer mapeo de uniones entre personas del mismo sexo en Brasil muestra que hubo 3.701 en 2013. Para el profesor Sergio Carrara (CLAM\/IMS\/UERJ), si bien es peque\u00f1o comparado con las uniones heterosexuales, el n\u00famero muestra la importancia de las pol\u00edticas de promoci\u00f3n de la ciudadan\u00eda LGBT. (Texto en portugu\u00e9s)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clam.org.br\/es\/noticias-clam\/numeros-del-matrimonio\/1015\/\" \/>\n<meta property=\"og:site_name\" content=\"CLAM - ES\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-14T02:00:00+00:00\" \/>\n<meta name=\"author\" content=\"fw2\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"fw2\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/noticias-clam\\\/numeros-del-matrimonio\\\/1015\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/noticias-clam\\\/numeros-del-matrimonio\\\/1015\\\/\"},\"author\":{\"name\":\"fw2\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#\\\/schema\\\/person\\\/fbd9a86032bf7479f94b0ded196f1010\"},\"headline\":\"N\u00fameros del matrimonio\",\"datePublished\":\"2015-01-14T02:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/noticias-clam\\\/numeros-del-matrimonio\\\/1015\\\/\"},\"wordCount\":1040,\"commentCount\":0,\"articleSection\":[\"noticias CLAM\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/clam.org.br\\\/es\\\/noticias-clam\\\/numeros-del-matrimonio\\\/1015\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/noticias-clam\\\/numeros-del-matrimonio\\\/1015\\\/\",\"url\":\"https:\\\/\\\/clam.org.br\\\/es\\\/noticias-clam\\\/numeros-del-matrimonio\\\/1015\\\/\",\"name\":\"N\u00fameros del matrimonio - CLAM - ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#website\"},\"datePublished\":\"2015-01-14T02:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#\\\/schema\\\/person\\\/fbd9a86032bf7479f94b0ded196f1010\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/noticias-clam\\\/numeros-del-matrimonio\\\/1015\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/clam.org.br\\\/es\\\/noticias-clam\\\/numeros-del-matrimonio\\\/1015\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/noticias-clam\\\/numeros-del-matrimonio\\\/1015\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/clam.org.br\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"N\u00fameros del matrimonio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/clam.org.br\\\/es\\\/\",\"name\":\"CLAM - ES\",\"description\":\"S\u00f3 mais um site CLAM - Centro Latino-Americano em Sexualidade e Direitos Humanos sites\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/clam.org.br\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#\\\/schema\\\/person\\\/fbd9a86032bf7479f94b0ded196f1010\",\"name\":\"fw2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g\",\"caption\":\"fw2\"},\"sameAs\":[\"https:\\\/\\\/clam.org.br\"],\"url\":\"https:\\\/\\\/clam.org.br\\\/es\\\/author\\\/fw2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"N\u00fameros del matrimonio - CLAM - ES","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clam.org.br\/es\/noticias-clam\/numeros-del-matrimonio\/1015\/","og_locale":"es_ES","og_type":"article","og_title":"N\u00fameros del matrimonio - CLAM - ES","og_description":"Primer mapeo de uniones entre personas del mismo sexo en Brasil muestra que hubo 3.701 en 2013. Para el profesor Sergio Carrara (CLAM\/IMS\/UERJ), si bien es peque\u00f1o comparado con las uniones heterosexuales, el n\u00famero muestra la importancia de las pol\u00edticas de promoci\u00f3n de la ciudadan\u00eda LGBT. (Texto en portugu\u00e9s)","og_url":"https:\/\/clam.org.br\/es\/noticias-clam\/numeros-del-matrimonio\/1015\/","og_site_name":"CLAM - ES","article_published_time":"2015-01-14T02:00:00+00:00","author":"fw2","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"fw2","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/clam.org.br\/es\/noticias-clam\/numeros-del-matrimonio\/1015\/#article","isPartOf":{"@id":"https:\/\/clam.org.br\/es\/noticias-clam\/numeros-del-matrimonio\/1015\/"},"author":{"name":"fw2","@id":"https:\/\/clam.org.br\/es\/#\/schema\/person\/fbd9a86032bf7479f94b0ded196f1010"},"headline":"N\u00fameros del matrimonio","datePublished":"2015-01-14T02:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/clam.org.br\/es\/noticias-clam\/numeros-del-matrimonio\/1015\/"},"wordCount":1040,"commentCount":0,"articleSection":["noticias CLAM"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/clam.org.br\/es\/noticias-clam\/numeros-del-matrimonio\/1015\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/clam.org.br\/es\/noticias-clam\/numeros-del-matrimonio\/1015\/","url":"https:\/\/clam.org.br\/es\/noticias-clam\/numeros-del-matrimonio\/1015\/","name":"N\u00fameros del matrimonio - CLAM - ES","isPartOf":{"@id":"https:\/\/clam.org.br\/es\/#website"},"datePublished":"2015-01-14T02:00:00+00:00","author":{"@id":"https:\/\/clam.org.br\/es\/#\/schema\/person\/fbd9a86032bf7479f94b0ded196f1010"},"breadcrumb":{"@id":"https:\/\/clam.org.br\/es\/noticias-clam\/numeros-del-matrimonio\/1015\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/clam.org.br\/es\/noticias-clam\/numeros-del-matrimonio\/1015\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/clam.org.br\/es\/noticias-clam\/numeros-del-matrimonio\/1015\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/clam.org.br\/es\/"},{"@type":"ListItem","position":2,"name":"N\u00fameros del matrimonio"}]},{"@type":"WebSite","@id":"https:\/\/clam.org.br\/es\/#website","url":"https:\/\/clam.org.br\/es\/","name":"CLAM - ES","description":"S\u00f3 mais um site CLAM - Centro Latino-Americano em Sexualidade e Direitos Humanos sites","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clam.org.br\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/clam.org.br\/es\/#\/schema\/person\/fbd9a86032bf7479f94b0ded196f1010","name":"fw2","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g","caption":"fw2"},"sameAs":["https:\/\/clam.org.br"],"url":"https:\/\/clam.org.br\/es\/author\/fw2\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/posts\/1015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/comments?post=1015"}],"version-history":[{"count":0,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/posts\/1015\/revisions"}],"wp:attachment":[{"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/media?parent=1015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/categories?post=1015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/tags?post=1015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}