{"id":1359,"date":"2007-07-12T00:00:00","date_gmt":"2007-07-12T03:00:00","guid":{"rendered":"https:\/\/clam.fw2web.com.br\/es\/2007\/07\/12\/ley-igualitaria\/"},"modified":"2007-07-12T00:00:00","modified_gmt":"2007-07-12T03:00:00","slug":"ley-igualitaria","status":"publish","type":"post","link":"https:\/\/clam.org.br\/es\/entrevistas\/ley-igualitaria\/1359\/","title":{"rendered":"Ley igualitaria"},"content":{"rendered":"<p>H\u00e1 30 anos o Congresso Nacional brasileiro aprovou a emenda que retirou da Constitui\u00e7\u00e3o a indissolubilidade do casamento, possibilitando a regulamenta\u00e7\u00e3o do div\u00f3rcio, por meio de lei. Segundo a \u00faltima pesquisa do Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE) sobre o estado civil dos brasileiros, em 2005 houve um div\u00f3rcio para cada 3 casamentos no Brasil, sobretudo entre as classes mais favorecidas. O estudo tamb\u00e9m revelou que nunca antes houve tantos casamentos em que ao menos um c\u00f4njuge estivesse j\u00e1 na segunda tentativa. No entanto as estat\u00edsticas mostram que s\u00e3o os homens que, no momento de se casar novamente, mais se beneficiam da lei. Eles t\u00eam, em m\u00e9dia, duas vezes mais chances de partir para a segunda uni\u00e3o legal do que as mulheres.<BR>  <P>De acordo com os pesquisadores respons\u00e1veis pelo estudo do IBGE, a desigualdade se deve ao fato de as mulheres sofrerem mais preconceito e de terem, em 91% dos casos, a responsabilidade de cuidar dos filhos, o que deixa os homens mais livres para tentar uma segunda rela\u00e7\u00e3o. Al\u00e9m disso, dizem os especialistas, devido ao aumento no n\u00edvel educacional das mulheres, quanto mais escolarizada for, menor ser\u00e1 a chance de encontrar um homem solteiro com o mesmo n\u00edvel de instru\u00e7\u00e3o. Em muitos casos, por\u00e9m, a decis\u00e3o de n\u00e3o se casar novamente ou de n\u00e3o formalizar uma segunda uni\u00e3o \u00e9 uma escolha da mulher.<BR>  <P>Para a dem\u00f3grafa Maria Coleta Oliveira, apesar dessas desigualdades, o div\u00f3rcio foi extremamente ben\u00e9fico para as mulheres. Na an\u00e1lise da professora do Departamento de Demografia e pesquisadora do N\u00facleo de Estudos de Popula\u00e7\u00e3o da Universidade Estadual de Campinas (NEPO\/UNICAMP), a lei n. 6.515, elaborada a partir de proposta do senador Nelson Carneiro e que regulamentava o div\u00f3rcio no Brasil, teve um significado muito importante. &ldquo;A sociedade brasileira era desigualmente permissiva em rela\u00e7\u00e3o aos homens, que podiam, sem grande reprova\u00e7\u00e3o, estabelecer outras rela\u00e7\u00f5es, concomitantes ou n\u00e3o, o que n\u00e3o se admitia em rela\u00e7\u00e3o \u00e0s mulheres&rdquo;, ressalta ela, nesta entrevista.<BR>  <P><B>Est\u00e1 fazendo 30 anos que o Congresso Nacional aprovou a Lei do Div\u00f3rcio. O que isso representou (e representa) para a sociedade e, em particular, para o campo da sexualidade?<\/B>  <P>Penso que a Lei do Div\u00f3rcio representou, \u00e0 \u00e9poca, uma resposta a algo que estava colocado pela sociedade. A curva de desquites crescia exponencialmente, revelando que o enquadramento legal era j\u00e1 insuficiente para dar conta das necessidades de as pessoas reorganizarem suas vidas ap\u00f3s o fim de um casamento. Representou, tamb\u00e9m, um reconhecimento de que homens e mulheres t\u00eam o direito de decidir encerrar um relacionamento insatisfat\u00f3rio por alguma raz\u00e3o. Para as mulheres, este reconhecimento teve um significado muito importante, j\u00e1 que desde h\u00e1 muito tempo a sociedade brasileira era desigualmente permissiva em rela\u00e7\u00e3o aos homens &#8211; que podiam sem grande reprova\u00e7\u00e3o, estabelecer outras rela\u00e7\u00f5es, concomitantes ou n\u00e3o, o que n\u00e3o se admitia em rela\u00e7\u00e3o \u00e0s mulheres.<BR>  <P>Com todos os problemas que ainda possam persistir, a Lei do Div\u00f3rcio trouxe uma normatiza\u00e7\u00e3o das rela\u00e7\u00f5es entre ex-parceiros, explicitando direitos e obriga\u00e7\u00f5es. A lei n\u00e3o trata de direitos sexuais. As uni\u00f5es reconhecidas legalmente s\u00e3o heterossexuais e monog\u00e2micas, e segue sendo assim. Mas pode-se pensar e argumentar que se homens e mulheres podem decidir encerrar um casamento insatisfat\u00f3rio, o exerc\u00edcio da sexualidade feminina com outro parceiro e ap\u00f3s a ruptura pelo div\u00f3rcio \u00e9 reconhecidamente um direito. A lei tamb\u00e9m n\u00e3o trata da sexualidade. Por\u00e9m, ao reconhecer igualdade de direitos a homens e mulheres, reconhece que ambos podem legitimamente estabelecer uma nova parceria sexual, j\u00e1 que o sexo \u00e9 um dos ingredientes do contrato de casamento.<BR>  <P><B>Mas, mesmo com a lei, as mulheres continuam sofrendo preconceito no momento de uma segunda uni\u00e3o. Os homens t\u00eam, em m\u00e9dia, duas vezes mais chances de partir para a segunda uni\u00e3o legal do que as mulheres.<\/B>  <P>Preconceitos existem, mas n\u00e3o creio que sejam a explica\u00e7\u00e3o para a maior freq\u00fc\u00eancia de segundos casamentos legais entre os homens. Pelo menos n\u00e3o no sentido de rea\u00e7\u00f5es negativas a uma segunda uni\u00e3o de mulheres. O que existe, sim, \u00e9 a perman\u00eancia do costume de que a mulher deva ser mais jovem e o homem mais velho em uma parceria conjugal. Isto restringe o mercado matrimonial de mulheres, como bem salientou Elza Berqu\u00f3 em seu j\u00e1 famoso texto &ldquo;Pir\u00e2mide da Solid\u00e3o&rdquo;. Se considerarmos a distribui\u00e7\u00e3o da popula\u00e7\u00e3o nas diferentes faixas de idade, o padr\u00e3o cultural vigente faz com que as mulheres olhem para as faixas acima de sua idade para procurar um novo parceiro. Os homens, diferentemente, olham para baixo, em busca de uma parceira mais jovem que ele. Em um contexto em que a expectativa de vida feminina \u00e9 mais elevada que a masculina, a vig\u00eancia de um preconceito de idade restringe ainda mais as oportunidades de uma mulher de casar-se novamente a medida que envelhece.<BR>  <P>Por\u00e9m, algumas tend\u00eancias recentes poder\u00e3o trazer mudan\u00e7as neste quadro. A forte valoriza\u00e7\u00e3o social das marcas da juventude \u00e9 ingrediente central das atitudes contempor\u00e2neas com rela\u00e7\u00e3o ao envelhecimento. Face ao prolongamento da vida, cada vez mais ouvimos, em un\u00edssono, recomenda\u00e7\u00f5es quanto \u00e0 boa forma para homens e mulheres que envelhecem. O sexo integra essas recomenda\u00e7\u00f5es, fortemente capitaneadas pelas terapias de reposi\u00e7\u00e3o hormonal para as mulheres ap\u00f3s a menopausa e pelos medicamentos que facilitam a ere\u00e7\u00e3o masculina, tipo viagra. Ora, \u00e9 poss\u00edvel pensar que estas inova\u00e7\u00f5es e os valores que as acompanham ampliem as possibilidades de parceria sexual entre homens e mulheres mais velhos e entre homens mais jovens do que suas parceiras.<BR>  <P><B>Os dados do \u00faltimo Censo do IBGE, de 2000, mostram que o crescimento no n\u00famero de div\u00f3rcios aconteceu principalmente em casais de n\u00edvel socioecon\u00f4mico mais elevado. Mostra ainda que a Educa\u00e7\u00e3o tamb\u00e9m pesa: entre brasileiros com n\u00edvel superior completo, o percentual de divorciados na popula\u00e7\u00e3o chega a 5%, enquanto o percentual de pessoas sem instru\u00e7\u00e3o que se divorciaram \u00e9 de apenas 1%. A sra. acha que as pessoas de menor escolaridade e renda divorciam menos ou formalizam (em cart\u00f3rio) menos suas uni\u00f5es, sem precisarem &ldquo;oficializar&rdquo; suas separa\u00e7\u00f5es?<\/B>  <P>O Registro Civil exclui todas as uni\u00f5es e separa\u00e7\u00f5es n\u00e3o formalizadas legalmente. Separa\u00e7\u00f5es de fato podem ocorrer em situa\u00e7\u00f5es em que h\u00e1 um casamento formal e nos casos de uni\u00f5es chamadas de consensuais. No caso dos censos, as informa\u00e7\u00f5es referem-se ao estado civil da popula\u00e7\u00e3o recenseada. Refere-se, portanto, a uma declara\u00e7\u00e3o fornecida pelo entrevistado. Embora os dados destas 2 fontes n\u00e3o sejam compar\u00e1veis, \u00e9 de se supor que aquelas pessoas que legalizaram sua separa\u00e7\u00e3o via div\u00f3rcio assim o declarem no censo. A mesma seguran\u00e7a n\u00e3o temos com rela\u00e7\u00e3o \u00e0 declara\u00e7\u00e3o de casado. Pessoas unidas consensualmente pela primeira vez &#8211; portanto solteiras &#8211; podem declarar-se casadas por assim o considerarem. Mas isto \u00e9 detalhe no contexto de sua preocupa\u00e7\u00e3o.<BR>  <P>Minha opini\u00e3o \u00e9 que as pessoas formalizam uni\u00f5es e separa\u00e7\u00f5es quando h\u00e1 interesses de que isso seja feito. Esses interesses t\u00eam a ver com pens\u00e3o de alimentos, partilha de propriedade e\/ou guarda de filhos, al\u00e9m do interesse em casar-se novamente, o que pode tamb\u00e9m levar \u00e0 formaliza\u00e7\u00e3o, pelo div\u00f3rcio, de uma separa\u00e7\u00e3o j\u00e1 ocorrida. Pode-se, portanto, supor que pessoas de camadas menos favorecidas tenham, deste ponto de vista, menos raz\u00f5es para formalizar uma separa\u00e7\u00e3o pela via do div\u00f3rcio. Minha experi\u00eancia com servi\u00e7os de assist\u00eancia p\u00fablica \u00e0 popula\u00e7\u00e3o de baixa renda em S\u00e3o Paulo \u00e9 de que os acordos de separa\u00e7\u00e3o tendem a ser informais, at\u00e9 que algum desentendimento no cumprimento dos acordos estabelecidos informalmente leve as pessoas a procurar formaliz\u00e1-los legalmente. A formaliza\u00e7\u00e3o legal \u00e9, nesse sentido, uma medida de prote\u00e7\u00e3o de direitos e assim \u00e9 vista pela clientela desses servi\u00e7os. Portanto, n\u00e3o me surpreende que a propor\u00e7\u00e3o de divorciados entre pessoas com maior n\u00edvel de escolaridade seja maior do que aquela entre os de escolaridade baixa ou entre pessoas sem instru\u00e7\u00e3o.<\/P><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace 30 a\u00f1os, fue aprobada la ley de divorcio en Brasil donde actualmente se registra un divorcio por cada 3 casamientos. Para la profesora Maria Coleta Oliveira, del Departamento de Demograf\u00eda de la UNICAMP, la ley tuvo un significado muy importante para las mujeres. <EM>(Texto en Portugu\u00e9s)<\/EM><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[8],"tags":[],"class_list":["post-1359","post","type-post","status-publish","format-standard","hentry","category-entrevistas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ley igualitaria - CLAM - ES<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clam.org.br\/es\/entrevistas\/ley-igualitaria\/1359\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ley igualitaria - CLAM - ES\" \/>\n<meta property=\"og:description\" content=\"Hace 30 a\u00f1os, fue aprobada la ley de divorcio en Brasil donde actualmente se registra un divorcio por cada 3 casamientos. Para la profesora Maria Coleta Oliveira, del Departamento de Demograf\u00eda de la UNICAMP, la ley tuvo un significado muy importante para las mujeres. (Texto en Portugu\u00e9s)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clam.org.br\/es\/entrevistas\/ley-igualitaria\/1359\/\" \/>\n<meta property=\"og:site_name\" content=\"CLAM - ES\" \/>\n<meta property=\"article:published_time\" content=\"2007-07-12T03:00:00+00:00\" \/>\n<meta name=\"author\" content=\"fw2\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"fw2\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/entrevistas\\\/ley-igualitaria\\\/1359\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/entrevistas\\\/ley-igualitaria\\\/1359\\\/\"},\"author\":{\"name\":\"fw2\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#\\\/schema\\\/person\\\/fbd9a86032bf7479f94b0ded196f1010\"},\"headline\":\"Ley igualitaria\",\"datePublished\":\"2007-07-12T03:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/entrevistas\\\/ley-igualitaria\\\/1359\\\/\"},\"wordCount\":1410,\"commentCount\":0,\"articleSection\":[\"Entrevistas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/clam.org.br\\\/es\\\/entrevistas\\\/ley-igualitaria\\\/1359\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/entrevistas\\\/ley-igualitaria\\\/1359\\\/\",\"url\":\"https:\\\/\\\/clam.org.br\\\/es\\\/entrevistas\\\/ley-igualitaria\\\/1359\\\/\",\"name\":\"Ley igualitaria - CLAM - ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#website\"},\"datePublished\":\"2007-07-12T03:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#\\\/schema\\\/person\\\/fbd9a86032bf7479f94b0ded196f1010\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/entrevistas\\\/ley-igualitaria\\\/1359\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/clam.org.br\\\/es\\\/entrevistas\\\/ley-igualitaria\\\/1359\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/entrevistas\\\/ley-igualitaria\\\/1359\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/clam.org.br\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ley igualitaria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/clam.org.br\\\/es\\\/\",\"name\":\"CLAM - ES\",\"description\":\"S\u00f3 mais um site CLAM - Centro Latino-Americano em Sexualidade e Direitos Humanos sites\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/clam.org.br\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#\\\/schema\\\/person\\\/fbd9a86032bf7479f94b0ded196f1010\",\"name\":\"fw2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g\",\"caption\":\"fw2\"},\"sameAs\":[\"https:\\\/\\\/clam.org.br\"],\"url\":\"https:\\\/\\\/clam.org.br\\\/es\\\/author\\\/fw2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ley igualitaria - CLAM - ES","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clam.org.br\/es\/entrevistas\/ley-igualitaria\/1359\/","og_locale":"es_ES","og_type":"article","og_title":"Ley igualitaria - CLAM - ES","og_description":"Hace 30 a\u00f1os, fue aprobada la ley de divorcio en Brasil donde actualmente se registra un divorcio por cada 3 casamientos. Para la profesora Maria Coleta Oliveira, del Departamento de Demograf\u00eda de la UNICAMP, la ley tuvo un significado muy importante para las mujeres. (Texto en Portugu\u00e9s)","og_url":"https:\/\/clam.org.br\/es\/entrevistas\/ley-igualitaria\/1359\/","og_site_name":"CLAM - ES","article_published_time":"2007-07-12T03:00:00+00:00","author":"fw2","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"fw2","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/clam.org.br\/es\/entrevistas\/ley-igualitaria\/1359\/#article","isPartOf":{"@id":"https:\/\/clam.org.br\/es\/entrevistas\/ley-igualitaria\/1359\/"},"author":{"name":"fw2","@id":"https:\/\/clam.org.br\/es\/#\/schema\/person\/fbd9a86032bf7479f94b0ded196f1010"},"headline":"Ley igualitaria","datePublished":"2007-07-12T03:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/clam.org.br\/es\/entrevistas\/ley-igualitaria\/1359\/"},"wordCount":1410,"commentCount":0,"articleSection":["Entrevistas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/clam.org.br\/es\/entrevistas\/ley-igualitaria\/1359\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/clam.org.br\/es\/entrevistas\/ley-igualitaria\/1359\/","url":"https:\/\/clam.org.br\/es\/entrevistas\/ley-igualitaria\/1359\/","name":"Ley igualitaria - CLAM - ES","isPartOf":{"@id":"https:\/\/clam.org.br\/es\/#website"},"datePublished":"2007-07-12T03:00:00+00:00","author":{"@id":"https:\/\/clam.org.br\/es\/#\/schema\/person\/fbd9a86032bf7479f94b0ded196f1010"},"breadcrumb":{"@id":"https:\/\/clam.org.br\/es\/entrevistas\/ley-igualitaria\/1359\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/clam.org.br\/es\/entrevistas\/ley-igualitaria\/1359\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/clam.org.br\/es\/entrevistas\/ley-igualitaria\/1359\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/clam.org.br\/es\/"},{"@type":"ListItem","position":2,"name":"Ley igualitaria"}]},{"@type":"WebSite","@id":"https:\/\/clam.org.br\/es\/#website","url":"https:\/\/clam.org.br\/es\/","name":"CLAM - ES","description":"S\u00f3 mais um site CLAM - Centro Latino-Americano em Sexualidade e Direitos Humanos sites","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clam.org.br\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/clam.org.br\/es\/#\/schema\/person\/fbd9a86032bf7479f94b0ded196f1010","name":"fw2","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g","caption":"fw2"},"sameAs":["https:\/\/clam.org.br"],"url":"https:\/\/clam.org.br\/es\/author\/fw2\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/posts\/1359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/comments?post=1359"}],"version-history":[{"count":0,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/posts\/1359\/revisions"}],"wp:attachment":[{"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/media?parent=1359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/categories?post=1359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/tags?post=1359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}