{"id":1374,"date":"2007-09-18T00:00:00","date_gmt":"2007-09-18T03:00:00","guid":{"rendered":"https:\/\/clam.fw2web.com.br\/es\/2007\/09\/18\/educar-en-la-sexualidad\/"},"modified":"2007-09-18T00:00:00","modified_gmt":"2007-09-18T03:00:00","slug":"educar-en-la-sexualidad","status":"publish","type":"post","link":"https:\/\/clam.org.br\/es\/entrevistas\/educar-en-la-sexualidad\/1374\/","title":{"rendered":"Educar en la sexualidad"},"content":{"rendered":"<p>Reci\u00e9n iniciado el a\u00f1o escolar, en M\u00e9xico se origin\u00f3 una discusi\u00f3n sobre los contenidos del libro de biolog\u00eda de educaci\u00f3n secundaria, ya que las m\u00e1s fuertes organizaciones conservadoras de inspiraci\u00f3n cat\u00f3lica se oponen a que se hable sobre masturbaci\u00f3n, homosexualidad y la p\u00edldora anticonceptiva de emergencia a adolescentes de 12 a\u00f1os.<BR>  <P>En este marco, el sex\u00f3logo Juan Luis \u00c1lvarez-Gayou, de amplia trayectoria al frente del Instituto Mexicano de Sexolog\u00eda, publica su libro Educaci\u00f3n de la sexualidad: \u00bfen la casa o en la escuela? El especialista propone como base de la educaci\u00f3n sexual la tarea de eliminar los estereotipos de g\u00e9nero. Es en estos paradigmas que se gesta la violencia intrafamiliar y la discriminaci\u00f3n de las mujeres. Para acabar con ello es necesario educar a los que educan: las y los profesores.<BR>  <P><B>\u00bfPor qu\u00e9, si el tema de la educaci\u00f3n sexual comenz\u00f3 a debatirse por primera vez en Am\u00e9rica Latina en 1930, sigue causando tanta pol\u00e9mica?<\/B>  <P>Creo que el tema crea una falsa pol\u00e9mica que tiene que ver con la voz de grupos ultraconservadores que, aun siendo minoritarios, tienen una voz muy fuerte. Esta ultraderecha ha tenido como reh\u00e9n a gobiernos que les tienen miedo y no quieren problemas con la Iglesia ni con grupos conservadores que, adem\u00e1s, coincidentemente, est\u00e1n emparentados con grupos de gran poder econ\u00f3mico.<BR>  <P>En M\u00e9xico, los gobiernos han tenido t\u00edmidos avances, como la promoci\u00f3n del uso del cond\u00f3n para prevenir el VIH\/sida o la instalaci\u00f3n de temas de sexualidad en quinto a\u00f1o de educaci\u00f3n primaria. No obstante, los temas que aparecen en los libros de texto no se apartan mucho de lo biol\u00f3gico, motivo por el que no resuelven nada. No se trata de meter m\u00e1s contenidos en los libros, se trata de educar en actitudes.<BR>  <P>Por esa raz\u00f3n en este libro propongo que la educaci\u00f3n de la sexualidad se imparta desde el preescolar, entendi\u00e9ndola de un modo integral, como aquella educaci\u00f3n que no s\u00f3lo da informaci\u00f3n sino que tambi\u00e9n genera actitudes adecuadas y valores. Esto no significa hablar con los ni\u00f1os de preescolar de coito, de orgasmo o de masturbaci\u00f3n, sino ir adecuando los textos para cada grupo de edad.<BR>  <P><B>Con la aparente divisi\u00f3n que existe actualmente en Am\u00e9rica Latina entre izquierdas y derechas, \u00bfpodr\u00edamos prever d\u00f3nde prosperar\u00e1n los avances en materia de educaci\u00f3n sexual?<\/B>  <P>Podr\u00edamos pensar que la izquierda fuera m\u00e1s liberal en materia de sexualidad, pero la sorpresa que muchos nos hemos llevado es que las izquierdas a veces son tanto o m\u00e1s conservadoras en temas de sexualidad que la derecha. Pienso que el tema de la sexualidad trasciende todo lo que son las ideolog\u00edas de izquierda y derecha.<BR>  <P>Creo que este tema no tiene tanto que ver con cuesti\u00f3n de izquierdas o derechas, sino con una visi\u00f3n de genuina preocupaci\u00f3n por los problemas sociales y de salud que conlleva la falta de educaci\u00f3n de la sexualidad.<BR>  <P>S\u00e9 por ejemplo que en Costa Rica y Guatemala el tema est\u00e1 muy trabado, pero creo que en M\u00e9xico podemos cambiar las cosas y espero que para bien.<BR>  <P><B>\u00bfCu\u00e1l es la situaci\u00f3n de Latinoam\u00e9rica frente al nuevo intento de la Iglesia Cat\u00f3lica de influir mundialmente silenciando estas tem\u00e1ticas?<\/B>  <P>Creo que es dif\u00edcil pensar a la Iglesia Cat\u00f3lica como un solo bloque. Una cosa son las jerarqu\u00edas y otra qui\u00e9nes est\u00e1n trabajando desde la trinchera. En ese sentido, creo que la jerarqu\u00eda est\u00e1 adquiriendo fuerza, pero tambi\u00e9n est\u00e1 muy golpeada por todas las acusaciones de abusos sexuales de sacerdotes.<BR>  <P>Yo no creo que la Iglesia vaya a estar en contra de esta iniciativa. De hecho cuando el a\u00f1o pasado se toc\u00f3 el tema de educaci\u00f3n sexual, el vocero de la Conferencia del Episcopado Mexicano dijo que estaban de acuerdo con que se diera educaci\u00f3n de la sexualidad y lo que les preocupaba era qui\u00e9n la impartir\u00eda. A final de cuentas es la misma preocupaci\u00f3n que tenemos nosotros, porque la educaci\u00f3n de la sexualidad, cuando es profesional, propicia el desarrollo de cuatro valores: respeto, responsabilidad, tolerancia y amor. Yo quiero saber qu\u00e9 credo religioso est\u00e1 en contra de estos cuatro valores.<BR>  <P><B>\u00bfC\u00f3mo romper la inercia de los estereotipos de g\u00e9nero en las escuelas?<\/B>  <P>En mi libro propongo una visi\u00f3n anestereot\u00edpica de los g\u00e9neros donde se estipula que desde el preescolar los y las docentes vean las potencialidades que tienen ni\u00f1os y ni\u00f1as independientemente de que se apeguen o no a los estereotipos de g\u00e9nero.<BR>  <P>Hombres y mujeres no somos tan diferentes, tenemos diferencias muy puntuales que podemos contar con los dedos de una mano. Son los estereotipos sociales que nos han impuesto los que hacen que nos sintamos tan diferentes unos de otras. Si se empieza a educar a ni\u00f1os y ni\u00f1as de preescolar lo m\u00e1s libre de estos estereotipos posible, cuando crezcan van a ser diferentes, lo que originar\u00e1 la posibilidad de un cambio social.<BR>  <P>La educaci\u00f3n ambiental, por ejemplo, no empez\u00f3 en la casa sino en las escuelas. Ahora todas las casas tienen uno o dos inspectores ambientales que les dicen a sus padres que separen la basura y no desperdicien el agua porque la escuela los educ\u00f3. Cuando esos ni\u00f1os sean adultos no van a hacer lo que hace hoy su pap\u00e1 o su mam\u00e1. Lo mismo puede suceder con el tema de g\u00e9nero.<\/P><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En M\u00e9xico, organizaciones conservadoras cat\u00f3licas se oponen a tratar la anticoncepci\u00f3n de emergencia, la masturbaci\u00f3n y la homosexualidad en la educaci\u00f3n secundaria. El sex\u00f3logo Juan Luis \u00c1lvarez-Gayou aborda la importancia de la educaci\u00f3n sexual en la escuela.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[8],"tags":[],"class_list":["post-1374","post","type-post","status-publish","format-standard","hentry","category-entrevistas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Educar en la sexualidad - CLAM - ES<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clam.org.br\/es\/entrevistas\/educar-en-la-sexualidad\/1374\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Educar en la sexualidad - CLAM - ES\" \/>\n<meta property=\"og:description\" content=\"En M\u00e9xico, organizaciones conservadoras cat\u00f3licas se oponen a tratar la anticoncepci\u00f3n de emergencia, la masturbaci\u00f3n y la homosexualidad en la educaci\u00f3n secundaria. El sex\u00f3logo Juan Luis \u00c1lvarez-Gayou aborda la importancia de la educaci\u00f3n sexual en la escuela.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clam.org.br\/es\/entrevistas\/educar-en-la-sexualidad\/1374\/\" \/>\n<meta property=\"og:site_name\" content=\"CLAM - ES\" \/>\n<meta property=\"article:published_time\" content=\"2007-09-18T03:00:00+00:00\" \/>\n<meta name=\"author\" content=\"fw2\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"fw2\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/entrevistas\\\/educar-en-la-sexualidad\\\/1374\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/entrevistas\\\/educar-en-la-sexualidad\\\/1374\\\/\"},\"author\":{\"name\":\"fw2\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#\\\/schema\\\/person\\\/fbd9a86032bf7479f94b0ded196f1010\"},\"headline\":\"Educar en la sexualidad\",\"datePublished\":\"2007-09-18T03:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/entrevistas\\\/educar-en-la-sexualidad\\\/1374\\\/\"},\"wordCount\":963,\"commentCount\":0,\"articleSection\":[\"Entrevistas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/clam.org.br\\\/es\\\/entrevistas\\\/educar-en-la-sexualidad\\\/1374\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/entrevistas\\\/educar-en-la-sexualidad\\\/1374\\\/\",\"url\":\"https:\\\/\\\/clam.org.br\\\/es\\\/entrevistas\\\/educar-en-la-sexualidad\\\/1374\\\/\",\"name\":\"Educar en la sexualidad - CLAM - ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#website\"},\"datePublished\":\"2007-09-18T03:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#\\\/schema\\\/person\\\/fbd9a86032bf7479f94b0ded196f1010\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/entrevistas\\\/educar-en-la-sexualidad\\\/1374\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/clam.org.br\\\/es\\\/entrevistas\\\/educar-en-la-sexualidad\\\/1374\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/entrevistas\\\/educar-en-la-sexualidad\\\/1374\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/clam.org.br\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Educar en la sexualidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/clam.org.br\\\/es\\\/\",\"name\":\"CLAM - ES\",\"description\":\"S\u00f3 mais um site CLAM - Centro Latino-Americano em Sexualidade e Direitos Humanos sites\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/clam.org.br\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#\\\/schema\\\/person\\\/fbd9a86032bf7479f94b0ded196f1010\",\"name\":\"fw2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g\",\"caption\":\"fw2\"},\"sameAs\":[\"https:\\\/\\\/clam.org.br\"],\"url\":\"https:\\\/\\\/clam.org.br\\\/es\\\/author\\\/fw2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Educar en la sexualidad - CLAM - ES","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clam.org.br\/es\/entrevistas\/educar-en-la-sexualidad\/1374\/","og_locale":"es_ES","og_type":"article","og_title":"Educar en la sexualidad - CLAM - ES","og_description":"En M\u00e9xico, organizaciones conservadoras cat\u00f3licas se oponen a tratar la anticoncepci\u00f3n de emergencia, la masturbaci\u00f3n y la homosexualidad en la educaci\u00f3n secundaria. El sex\u00f3logo Juan Luis \u00c1lvarez-Gayou aborda la importancia de la educaci\u00f3n sexual en la escuela.","og_url":"https:\/\/clam.org.br\/es\/entrevistas\/educar-en-la-sexualidad\/1374\/","og_site_name":"CLAM - ES","article_published_time":"2007-09-18T03:00:00+00:00","author":"fw2","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"fw2","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/clam.org.br\/es\/entrevistas\/educar-en-la-sexualidad\/1374\/#article","isPartOf":{"@id":"https:\/\/clam.org.br\/es\/entrevistas\/educar-en-la-sexualidad\/1374\/"},"author":{"name":"fw2","@id":"https:\/\/clam.org.br\/es\/#\/schema\/person\/fbd9a86032bf7479f94b0ded196f1010"},"headline":"Educar en la sexualidad","datePublished":"2007-09-18T03:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/clam.org.br\/es\/entrevistas\/educar-en-la-sexualidad\/1374\/"},"wordCount":963,"commentCount":0,"articleSection":["Entrevistas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/clam.org.br\/es\/entrevistas\/educar-en-la-sexualidad\/1374\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/clam.org.br\/es\/entrevistas\/educar-en-la-sexualidad\/1374\/","url":"https:\/\/clam.org.br\/es\/entrevistas\/educar-en-la-sexualidad\/1374\/","name":"Educar en la sexualidad - CLAM - ES","isPartOf":{"@id":"https:\/\/clam.org.br\/es\/#website"},"datePublished":"2007-09-18T03:00:00+00:00","author":{"@id":"https:\/\/clam.org.br\/es\/#\/schema\/person\/fbd9a86032bf7479f94b0ded196f1010"},"breadcrumb":{"@id":"https:\/\/clam.org.br\/es\/entrevistas\/educar-en-la-sexualidad\/1374\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/clam.org.br\/es\/entrevistas\/educar-en-la-sexualidad\/1374\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/clam.org.br\/es\/entrevistas\/educar-en-la-sexualidad\/1374\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/clam.org.br\/es\/"},{"@type":"ListItem","position":2,"name":"Educar en la sexualidad"}]},{"@type":"WebSite","@id":"https:\/\/clam.org.br\/es\/#website","url":"https:\/\/clam.org.br\/es\/","name":"CLAM - ES","description":"S\u00f3 mais um site CLAM - Centro Latino-Americano em Sexualidade e Direitos Humanos sites","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clam.org.br\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/clam.org.br\/es\/#\/schema\/person\/fbd9a86032bf7479f94b0ded196f1010","name":"fw2","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g","caption":"fw2"},"sameAs":["https:\/\/clam.org.br"],"url":"https:\/\/clam.org.br\/es\/author\/fw2\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/posts\/1374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/comments?post=1374"}],"version-history":[{"count":0,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/posts\/1374\/revisions"}],"wp:attachment":[{"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/media?parent=1374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/categories?post=1374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/tags?post=1374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}