{"id":29574,"date":"2006-01-24T00:00:00","date_gmt":"2006-01-24T02:00:00","guid":{"rendered":"https:\/\/clam.fw2web.com.br\/es\/2006\/01\/24\/a-partir-de-febrero-capacitaran-a-mujeres-de-barranquilla-para-luchar-contra-la-violencia\/"},"modified":"2006-01-24T00:00:00","modified_gmt":"2006-01-24T02:00:00","slug":"a-partir-de-febrero-capacitaran-a-mujeres-de-barranquilla-para-luchar-contra-la-violencia","status":"publish","type":"post","link":"https:\/\/clam.org.br\/es\/en-los-medios\/a-partir-de-febrero-capacitaran-a-mujeres-de-barranquilla-para-luchar-contra-la-violencia\/29574\/","title":{"rendered":"A partir de febrero, capacitar\u00e1n a mujeres de Barranquilla para luchar contra la violencia"},"content":{"rendered":"<p>Varias organizaciones no gubernamentales de la ciudad presentaron el proyecto, escogido como \u00fanico en America Latina por el Fondo de Naciones Unidas.<BR> <BR> <a href=\"http:\/\/eltiempo.terra.com.co\/naci\/cari\/2006-01-17\/ARTICULO-WEB-_NOTA_INTERIOR-2696311.html\" target=\"_blank\" rel=\"noopener\">Texto completo.<\/A><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Varias organizaciones no gubernamentales de la ciudad presentaron el proyecto, escogido como \u00fanico en America Latina por el Fondo de Naciones Unidas.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[27],"tags":[],"class_list":["post-29574","post","type-post","status-publish","format-standard","hentry","category-en-los-medios"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A partir de febrero, capacitar\u00e1n a mujeres de Barranquilla para luchar contra la violencia - CLAM - ES<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clam.org.br\/es\/en-los-medios\/a-partir-de-febrero-capacitaran-a-mujeres-de-barranquilla-para-luchar-contra-la-violencia\/29574\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A partir de febrero, capacitar\u00e1n a mujeres de Barranquilla para luchar contra la violencia - CLAM - ES\" \/>\n<meta property=\"og:description\" content=\"Varias organizaciones no gubernamentales de la ciudad presentaron el proyecto, escogido como \u00fanico en America Latina por el Fondo de Naciones Unidas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clam.org.br\/es\/en-los-medios\/a-partir-de-febrero-capacitaran-a-mujeres-de-barranquilla-para-luchar-contra-la-violencia\/29574\/\" \/>\n<meta property=\"og:site_name\" content=\"CLAM - ES\" \/>\n<meta property=\"article:published_time\" content=\"2006-01-24T02:00:00+00:00\" \/>\n<meta name=\"author\" content=\"fw2\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"fw2\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/en-los-medios\\\/a-partir-de-febrero-capacitaran-a-mujeres-de-barranquilla-para-luchar-contra-la-violencia\\\/29574\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/en-los-medios\\\/a-partir-de-febrero-capacitaran-a-mujeres-de-barranquilla-para-luchar-contra-la-violencia\\\/29574\\\/\"},\"author\":{\"name\":\"fw2\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#\\\/schema\\\/person\\\/fbd9a86032bf7479f94b0ded196f1010\"},\"headline\":\"A partir de febrero, capacitar\u00e1n a mujeres de Barranquilla para luchar contra la violencia\",\"datePublished\":\"2006-01-24T02:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/en-los-medios\\\/a-partir-de-febrero-capacitaran-a-mujeres-de-barranquilla-para-luchar-contra-la-violencia\\\/29574\\\/\"},\"wordCount\":39,\"commentCount\":0,\"articleSection\":[\"En los medios\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/clam.org.br\\\/es\\\/en-los-medios\\\/a-partir-de-febrero-capacitaran-a-mujeres-de-barranquilla-para-luchar-contra-la-violencia\\\/29574\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/en-los-medios\\\/a-partir-de-febrero-capacitaran-a-mujeres-de-barranquilla-para-luchar-contra-la-violencia\\\/29574\\\/\",\"url\":\"https:\\\/\\\/clam.org.br\\\/es\\\/en-los-medios\\\/a-partir-de-febrero-capacitaran-a-mujeres-de-barranquilla-para-luchar-contra-la-violencia\\\/29574\\\/\",\"name\":\"A partir de febrero, capacitar\u00e1n a mujeres de Barranquilla para luchar contra la violencia - CLAM - ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#website\"},\"datePublished\":\"2006-01-24T02:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#\\\/schema\\\/person\\\/fbd9a86032bf7479f94b0ded196f1010\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/en-los-medios\\\/a-partir-de-febrero-capacitaran-a-mujeres-de-barranquilla-para-luchar-contra-la-violencia\\\/29574\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/clam.org.br\\\/es\\\/en-los-medios\\\/a-partir-de-febrero-capacitaran-a-mujeres-de-barranquilla-para-luchar-contra-la-violencia\\\/29574\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/en-los-medios\\\/a-partir-de-febrero-capacitaran-a-mujeres-de-barranquilla-para-luchar-contra-la-violencia\\\/29574\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/clam.org.br\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A partir de febrero, capacitar\u00e1n a mujeres de Barranquilla para luchar contra la violencia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/clam.org.br\\\/es\\\/\",\"name\":\"CLAM - ES\",\"description\":\"S\u00f3 mais um site CLAM - Centro Latino-Americano em Sexualidade e Direitos Humanos sites\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/clam.org.br\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#\\\/schema\\\/person\\\/fbd9a86032bf7479f94b0ded196f1010\",\"name\":\"fw2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g\",\"caption\":\"fw2\"},\"sameAs\":[\"https:\\\/\\\/clam.org.br\"],\"url\":\"https:\\\/\\\/clam.org.br\\\/es\\\/author\\\/fw2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A partir de febrero, capacitar\u00e1n a mujeres de Barranquilla para luchar contra la violencia - CLAM - ES","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clam.org.br\/es\/en-los-medios\/a-partir-de-febrero-capacitaran-a-mujeres-de-barranquilla-para-luchar-contra-la-violencia\/29574\/","og_locale":"es_ES","og_type":"article","og_title":"A partir de febrero, capacitar\u00e1n a mujeres de Barranquilla para luchar contra la violencia - CLAM - ES","og_description":"Varias organizaciones no gubernamentales de la ciudad presentaron el proyecto, escogido como \u00fanico en America Latina por el Fondo de Naciones Unidas.","og_url":"https:\/\/clam.org.br\/es\/en-los-medios\/a-partir-de-febrero-capacitaran-a-mujeres-de-barranquilla-para-luchar-contra-la-violencia\/29574\/","og_site_name":"CLAM - ES","article_published_time":"2006-01-24T02:00:00+00:00","author":"fw2","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"fw2"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/clam.org.br\/es\/en-los-medios\/a-partir-de-febrero-capacitaran-a-mujeres-de-barranquilla-para-luchar-contra-la-violencia\/29574\/#article","isPartOf":{"@id":"https:\/\/clam.org.br\/es\/en-los-medios\/a-partir-de-febrero-capacitaran-a-mujeres-de-barranquilla-para-luchar-contra-la-violencia\/29574\/"},"author":{"name":"fw2","@id":"https:\/\/clam.org.br\/es\/#\/schema\/person\/fbd9a86032bf7479f94b0ded196f1010"},"headline":"A partir de febrero, capacitar\u00e1n a mujeres de Barranquilla para luchar contra la violencia","datePublished":"2006-01-24T02:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/clam.org.br\/es\/en-los-medios\/a-partir-de-febrero-capacitaran-a-mujeres-de-barranquilla-para-luchar-contra-la-violencia\/29574\/"},"wordCount":39,"commentCount":0,"articleSection":["En los medios"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/clam.org.br\/es\/en-los-medios\/a-partir-de-febrero-capacitaran-a-mujeres-de-barranquilla-para-luchar-contra-la-violencia\/29574\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/clam.org.br\/es\/en-los-medios\/a-partir-de-febrero-capacitaran-a-mujeres-de-barranquilla-para-luchar-contra-la-violencia\/29574\/","url":"https:\/\/clam.org.br\/es\/en-los-medios\/a-partir-de-febrero-capacitaran-a-mujeres-de-barranquilla-para-luchar-contra-la-violencia\/29574\/","name":"A partir de febrero, capacitar\u00e1n a mujeres de Barranquilla para luchar contra la violencia - CLAM - ES","isPartOf":{"@id":"https:\/\/clam.org.br\/es\/#website"},"datePublished":"2006-01-24T02:00:00+00:00","author":{"@id":"https:\/\/clam.org.br\/es\/#\/schema\/person\/fbd9a86032bf7479f94b0ded196f1010"},"breadcrumb":{"@id":"https:\/\/clam.org.br\/es\/en-los-medios\/a-partir-de-febrero-capacitaran-a-mujeres-de-barranquilla-para-luchar-contra-la-violencia\/29574\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/clam.org.br\/es\/en-los-medios\/a-partir-de-febrero-capacitaran-a-mujeres-de-barranquilla-para-luchar-contra-la-violencia\/29574\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/clam.org.br\/es\/en-los-medios\/a-partir-de-febrero-capacitaran-a-mujeres-de-barranquilla-para-luchar-contra-la-violencia\/29574\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/clam.org.br\/es\/"},{"@type":"ListItem","position":2,"name":"A partir de febrero, capacitar\u00e1n a mujeres de Barranquilla para luchar contra la violencia"}]},{"@type":"WebSite","@id":"https:\/\/clam.org.br\/es\/#website","url":"https:\/\/clam.org.br\/es\/","name":"CLAM - ES","description":"S\u00f3 mais um site CLAM - Centro Latino-Americano em Sexualidade e Direitos Humanos sites","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clam.org.br\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/clam.org.br\/es\/#\/schema\/person\/fbd9a86032bf7479f94b0ded196f1010","name":"fw2","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g","caption":"fw2"},"sameAs":["https:\/\/clam.org.br"],"url":"https:\/\/clam.org.br\/es\/author\/fw2\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/posts\/29574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/comments?post=29574"}],"version-history":[{"count":0,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/posts\/29574\/revisions"}],"wp:attachment":[{"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/media?parent=29574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/categories?post=29574"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/tags?post=29574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}