{"id":31996,"date":"2011-05-01T00:00:00","date_gmt":"2011-05-01T03:00:00","guid":{"rendered":"https:\/\/clam.fw2web.com.br\/es\/2011\/05\/01\/el-salvador-aborto-prohibido-muerte-o-carcel-seguras\/"},"modified":"2011-05-01T00:00:00","modified_gmt":"2011-05-01T03:00:00","slug":"el-salvador-aborto-prohibido-muerte-o-carcel-seguras","status":"publish","type":"post","link":"https:\/\/clam.org.br\/es\/en-los-medios\/el-salvador-aborto-prohibido-muerte-o-carcel-seguras\/31996\/","title":{"rendered":"El Salvador: aborto prohibido, muerte o c\u00e1rcel seguras"},"content":{"rendered":"<p><P>Mar\u00eda Edis se golpe\u00f3 el vientre tres d\u00edas antes de abortar. Del quir\u00f3fano pas\u00f3 a las bartolinas, de las bartolinas a la c\u00e1rcel y de la c\u00e1rcel a la tumba. Ten\u00eda 31 a\u00f1os. Cristina ten\u00eda 18 a\u00f1os cuando perdi\u00f3 a su segundo hijo y fue castigada con 30 a\u00f1os de prisi\u00f3n. Una revisi\u00f3n de su caso determin\u00f3 que los jueces se excedieron y qued\u00f3 libre cuando ya hab\u00eda estado presa m\u00e1s tiempo que el que ameritaba&rdquo;.<\/P> <P><U><a href=\"http:\/\/www.cimacnoticias.com\/site\/11042902-El-Salvador-aborto.46908.0.html\" target=\"_blank\" rel=\"noopener\">Texto completo<\/A><\/U><\/P><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mar\u00eda Edis se golpe\u00f3 el vientre tres d\u00edas antes de abortar. Del quir\u00f3fano pas\u00f3 a las bartolinas, de las bartolinas a la c\u00e1rcel y de la c\u00e1rcel a la tumba. Ten\u00eda 31 a\u00f1os. Cristina ten\u00eda 18 a\u00f1os cuando perdi\u00f3 a su segundo hijo y fue castigada con 30 a\u00f1os de prisi\u00f3n. Una revisi\u00f3n de su caso determin\u00f3 que los jueces se excedieron y qued\u00f3 libre cuando ya hab\u00eda estado presa m\u00e1s tiempo que el que ameritaba&rdquo;.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[27],"tags":[],"class_list":["post-31996","post","type-post","status-publish","format-standard","hentry","category-en-los-medios"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Salvador: aborto prohibido, muerte o c\u00e1rcel seguras - CLAM - ES<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clam.org.br\/es\/en-los-medios\/el-salvador-aborto-prohibido-muerte-o-carcel-seguras\/31996\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Salvador: aborto prohibido, muerte o c\u00e1rcel seguras - CLAM - ES\" \/>\n<meta property=\"og:description\" content=\"Mar\u00eda Edis se golpe\u00f3 el vientre tres d\u00edas antes de abortar. Del quir\u00f3fano pas\u00f3 a las bartolinas, de las bartolinas a la c\u00e1rcel y de la c\u00e1rcel a la tumba. Ten\u00eda 31 a\u00f1os. Cristina ten\u00eda 18 a\u00f1os cuando perdi\u00f3 a su segundo hijo y fue castigada con 30 a\u00f1os de prisi\u00f3n. Una revisi\u00f3n de su caso determin\u00f3 que los jueces se excedieron y qued\u00f3 libre cuando ya hab\u00eda estado presa m\u00e1s tiempo que el que ameritaba&rdquo;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clam.org.br\/es\/en-los-medios\/el-salvador-aborto-prohibido-muerte-o-carcel-seguras\/31996\/\" \/>\n<meta property=\"og:site_name\" content=\"CLAM - ES\" \/>\n<meta property=\"article:published_time\" content=\"2011-05-01T03:00:00+00:00\" \/>\n<meta name=\"author\" content=\"fw2\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"fw2\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/en-los-medios\\\/el-salvador-aborto-prohibido-muerte-o-carcel-seguras\\\/31996\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/en-los-medios\\\/el-salvador-aborto-prohibido-muerte-o-carcel-seguras\\\/31996\\\/\"},\"author\":{\"name\":\"fw2\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#\\\/schema\\\/person\\\/fbd9a86032bf7479f94b0ded196f1010\"},\"headline\":\"El Salvador: aborto prohibido, muerte o c\u00e1rcel seguras\",\"datePublished\":\"2011-05-01T03:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/en-los-medios\\\/el-salvador-aborto-prohibido-muerte-o-carcel-seguras\\\/31996\\\/\"},\"wordCount\":99,\"commentCount\":0,\"articleSection\":[\"En los medios\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/clam.org.br\\\/es\\\/en-los-medios\\\/el-salvador-aborto-prohibido-muerte-o-carcel-seguras\\\/31996\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/en-los-medios\\\/el-salvador-aborto-prohibido-muerte-o-carcel-seguras\\\/31996\\\/\",\"url\":\"https:\\\/\\\/clam.org.br\\\/es\\\/en-los-medios\\\/el-salvador-aborto-prohibido-muerte-o-carcel-seguras\\\/31996\\\/\",\"name\":\"El Salvador: aborto prohibido, muerte o c\u00e1rcel seguras - CLAM - ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#website\"},\"datePublished\":\"2011-05-01T03:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#\\\/schema\\\/person\\\/fbd9a86032bf7479f94b0ded196f1010\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/en-los-medios\\\/el-salvador-aborto-prohibido-muerte-o-carcel-seguras\\\/31996\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/clam.org.br\\\/es\\\/en-los-medios\\\/el-salvador-aborto-prohibido-muerte-o-carcel-seguras\\\/31996\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/en-los-medios\\\/el-salvador-aborto-prohibido-muerte-o-carcel-seguras\\\/31996\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/clam.org.br\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Salvador: aborto prohibido, muerte o c\u00e1rcel seguras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/clam.org.br\\\/es\\\/\",\"name\":\"CLAM - ES\",\"description\":\"S\u00f3 mais um site CLAM - Centro Latino-Americano em Sexualidade e Direitos Humanos sites\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/clam.org.br\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#\\\/schema\\\/person\\\/fbd9a86032bf7479f94b0ded196f1010\",\"name\":\"fw2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g\",\"caption\":\"fw2\"},\"sameAs\":[\"https:\\\/\\\/clam.org.br\"],\"url\":\"https:\\\/\\\/clam.org.br\\\/es\\\/author\\\/fw2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Salvador: aborto prohibido, muerte o c\u00e1rcel seguras - CLAM - ES","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clam.org.br\/es\/en-los-medios\/el-salvador-aborto-prohibido-muerte-o-carcel-seguras\/31996\/","og_locale":"es_ES","og_type":"article","og_title":"El Salvador: aborto prohibido, muerte o c\u00e1rcel seguras - CLAM - ES","og_description":"Mar\u00eda Edis se golpe\u00f3 el vientre tres d\u00edas antes de abortar. Del quir\u00f3fano pas\u00f3 a las bartolinas, de las bartolinas a la c\u00e1rcel y de la c\u00e1rcel a la tumba. Ten\u00eda 31 a\u00f1os. Cristina ten\u00eda 18 a\u00f1os cuando perdi\u00f3 a su segundo hijo y fue castigada con 30 a\u00f1os de prisi\u00f3n. Una revisi\u00f3n de su caso determin\u00f3 que los jueces se excedieron y qued\u00f3 libre cuando ya hab\u00eda estado presa m\u00e1s tiempo que el que ameritaba&rdquo;.","og_url":"https:\/\/clam.org.br\/es\/en-los-medios\/el-salvador-aborto-prohibido-muerte-o-carcel-seguras\/31996\/","og_site_name":"CLAM - ES","article_published_time":"2011-05-01T03:00:00+00:00","author":"fw2","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"fw2"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/clam.org.br\/es\/en-los-medios\/el-salvador-aborto-prohibido-muerte-o-carcel-seguras\/31996\/#article","isPartOf":{"@id":"https:\/\/clam.org.br\/es\/en-los-medios\/el-salvador-aborto-prohibido-muerte-o-carcel-seguras\/31996\/"},"author":{"name":"fw2","@id":"https:\/\/clam.org.br\/es\/#\/schema\/person\/fbd9a86032bf7479f94b0ded196f1010"},"headline":"El Salvador: aborto prohibido, muerte o c\u00e1rcel seguras","datePublished":"2011-05-01T03:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/clam.org.br\/es\/en-los-medios\/el-salvador-aborto-prohibido-muerte-o-carcel-seguras\/31996\/"},"wordCount":99,"commentCount":0,"articleSection":["En los medios"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/clam.org.br\/es\/en-los-medios\/el-salvador-aborto-prohibido-muerte-o-carcel-seguras\/31996\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/clam.org.br\/es\/en-los-medios\/el-salvador-aborto-prohibido-muerte-o-carcel-seguras\/31996\/","url":"https:\/\/clam.org.br\/es\/en-los-medios\/el-salvador-aborto-prohibido-muerte-o-carcel-seguras\/31996\/","name":"El Salvador: aborto prohibido, muerte o c\u00e1rcel seguras - CLAM - ES","isPartOf":{"@id":"https:\/\/clam.org.br\/es\/#website"},"datePublished":"2011-05-01T03:00:00+00:00","author":{"@id":"https:\/\/clam.org.br\/es\/#\/schema\/person\/fbd9a86032bf7479f94b0ded196f1010"},"breadcrumb":{"@id":"https:\/\/clam.org.br\/es\/en-los-medios\/el-salvador-aborto-prohibido-muerte-o-carcel-seguras\/31996\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/clam.org.br\/es\/en-los-medios\/el-salvador-aborto-prohibido-muerte-o-carcel-seguras\/31996\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/clam.org.br\/es\/en-los-medios\/el-salvador-aborto-prohibido-muerte-o-carcel-seguras\/31996\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/clam.org.br\/es\/"},{"@type":"ListItem","position":2,"name":"El Salvador: aborto prohibido, muerte o c\u00e1rcel seguras"}]},{"@type":"WebSite","@id":"https:\/\/clam.org.br\/es\/#website","url":"https:\/\/clam.org.br\/es\/","name":"CLAM - ES","description":"S\u00f3 mais um site CLAM - Centro Latino-Americano em Sexualidade e Direitos Humanos sites","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clam.org.br\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/clam.org.br\/es\/#\/schema\/person\/fbd9a86032bf7479f94b0ded196f1010","name":"fw2","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g","caption":"fw2"},"sameAs":["https:\/\/clam.org.br"],"url":"https:\/\/clam.org.br\/es\/author\/fw2\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/posts\/31996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/comments?post=31996"}],"version-history":[{"count":0,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/posts\/31996\/revisions"}],"wp:attachment":[{"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/media?parent=31996"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/categories?post=31996"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/tags?post=31996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}