{"id":32077,"date":"2011-06-21T00:00:00","date_gmt":"2011-06-21T03:00:00","guid":{"rendered":"https:\/\/clam.fw2web.com.br\/es\/2011\/06\/21\/mas-del-20-de-homosexuales-en-mexico-tienen-vih-oms\/"},"modified":"2011-06-21T00:00:00","modified_gmt":"2011-06-21T03:00:00","slug":"mas-del-20-de-homosexuales-en-mexico-tienen-vih-oms","status":"publish","type":"post","link":"https:\/\/clam.org.br\/es\/en-los-medios\/mas-del-20-de-homosexuales-en-mexico-tienen-vih-oms\/32077\/","title":{"rendered":"M\u00e1s del 20% de homosexuales en M\u00e9xico tienen VIH: OMS"},"content":{"rendered":"<p><P>Los homosexuales presentan 20 veces m\u00e1s probabilidades de contraer el VIH y por eso la Organizaci\u00f3n Mundial de la Salud (OMS) ha elaborado por primera vez una lista de directrices para el tratamiento y la prevenci\u00f3n de este virus entre el colectivo de homosexuales y transexuales. <\/P> <P><U><a href=\"http:\/\/www.eluniversal.com.mx\/notas\/773962.html\" target=\"_blank\" rel=\"noopener\">Texto completo<\/A><\/U><\/P><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los homosexuales presentan 20 veces m\u00e1s probabilidades de contraer el VIH y por eso la Organizaci\u00f3n Mundial de la Salud (OMS) ha elaborado por primera vez una lista de directrices para el tratamiento y la prevenci\u00f3n de este virus entre el colectivo de homosexuales y transexuales.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[27],"tags":[],"class_list":["post-32077","post","type-post","status-publish","format-standard","hentry","category-en-los-medios"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e1s del 20% de homosexuales en M\u00e9xico tienen VIH: OMS - CLAM - ES<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clam.org.br\/es\/en-los-medios\/mas-del-20-de-homosexuales-en-mexico-tienen-vih-oms\/32077\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e1s del 20% de homosexuales en M\u00e9xico tienen VIH: OMS - CLAM - ES\" \/>\n<meta property=\"og:description\" content=\"Los homosexuales presentan 20 veces m\u00e1s probabilidades de contraer el VIH y por eso la Organizaci\u00f3n Mundial de la Salud (OMS) ha elaborado por primera vez una lista de directrices para el tratamiento y la prevenci\u00f3n de este virus entre el colectivo de homosexuales y transexuales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clam.org.br\/es\/en-los-medios\/mas-del-20-de-homosexuales-en-mexico-tienen-vih-oms\/32077\/\" \/>\n<meta property=\"og:site_name\" content=\"CLAM - ES\" \/>\n<meta property=\"article:published_time\" content=\"2011-06-21T03:00:00+00:00\" \/>\n<meta name=\"author\" content=\"fw2\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"fw2\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/en-los-medios\\\/mas-del-20-de-homosexuales-en-mexico-tienen-vih-oms\\\/32077\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/en-los-medios\\\/mas-del-20-de-homosexuales-en-mexico-tienen-vih-oms\\\/32077\\\/\"},\"author\":{\"name\":\"fw2\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#\\\/schema\\\/person\\\/fbd9a86032bf7479f94b0ded196f1010\"},\"headline\":\"M\u00e1s del 20% de homosexuales en M\u00e9xico tienen VIH: OMS\",\"datePublished\":\"2011-06-21T03:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/en-los-medios\\\/mas-del-20-de-homosexuales-en-mexico-tienen-vih-oms\\\/32077\\\/\"},\"wordCount\":61,\"commentCount\":0,\"articleSection\":[\"En los medios\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/clam.org.br\\\/es\\\/en-los-medios\\\/mas-del-20-de-homosexuales-en-mexico-tienen-vih-oms\\\/32077\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/en-los-medios\\\/mas-del-20-de-homosexuales-en-mexico-tienen-vih-oms\\\/32077\\\/\",\"url\":\"https:\\\/\\\/clam.org.br\\\/es\\\/en-los-medios\\\/mas-del-20-de-homosexuales-en-mexico-tienen-vih-oms\\\/32077\\\/\",\"name\":\"M\u00e1s del 20% de homosexuales en M\u00e9xico tienen VIH: OMS - CLAM - ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#website\"},\"datePublished\":\"2011-06-21T03:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#\\\/schema\\\/person\\\/fbd9a86032bf7479f94b0ded196f1010\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/en-los-medios\\\/mas-del-20-de-homosexuales-en-mexico-tienen-vih-oms\\\/32077\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/clam.org.br\\\/es\\\/en-los-medios\\\/mas-del-20-de-homosexuales-en-mexico-tienen-vih-oms\\\/32077\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/en-los-medios\\\/mas-del-20-de-homosexuales-en-mexico-tienen-vih-oms\\\/32077\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/clam.org.br\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e1s del 20% de homosexuales en M\u00e9xico tienen VIH: OMS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/clam.org.br\\\/es\\\/\",\"name\":\"CLAM - ES\",\"description\":\"S\u00f3 mais um site CLAM - Centro Latino-Americano em Sexualidade e Direitos Humanos sites\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/clam.org.br\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#\\\/schema\\\/person\\\/fbd9a86032bf7479f94b0ded196f1010\",\"name\":\"fw2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g\",\"caption\":\"fw2\"},\"sameAs\":[\"https:\\\/\\\/clam.org.br\"],\"url\":\"https:\\\/\\\/clam.org.br\\\/es\\\/author\\\/fw2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e1s del 20% de homosexuales en M\u00e9xico tienen VIH: OMS - CLAM - ES","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clam.org.br\/es\/en-los-medios\/mas-del-20-de-homosexuales-en-mexico-tienen-vih-oms\/32077\/","og_locale":"es_ES","og_type":"article","og_title":"M\u00e1s del 20% de homosexuales en M\u00e9xico tienen VIH: OMS - CLAM - ES","og_description":"Los homosexuales presentan 20 veces m\u00e1s probabilidades de contraer el VIH y por eso la Organizaci\u00f3n Mundial de la Salud (OMS) ha elaborado por primera vez una lista de directrices para el tratamiento y la prevenci\u00f3n de este virus entre el colectivo de homosexuales y transexuales.","og_url":"https:\/\/clam.org.br\/es\/en-los-medios\/mas-del-20-de-homosexuales-en-mexico-tienen-vih-oms\/32077\/","og_site_name":"CLAM - ES","article_published_time":"2011-06-21T03:00:00+00:00","author":"fw2","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"fw2"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/clam.org.br\/es\/en-los-medios\/mas-del-20-de-homosexuales-en-mexico-tienen-vih-oms\/32077\/#article","isPartOf":{"@id":"https:\/\/clam.org.br\/es\/en-los-medios\/mas-del-20-de-homosexuales-en-mexico-tienen-vih-oms\/32077\/"},"author":{"name":"fw2","@id":"https:\/\/clam.org.br\/es\/#\/schema\/person\/fbd9a86032bf7479f94b0ded196f1010"},"headline":"M\u00e1s del 20% de homosexuales en M\u00e9xico tienen VIH: OMS","datePublished":"2011-06-21T03:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/clam.org.br\/es\/en-los-medios\/mas-del-20-de-homosexuales-en-mexico-tienen-vih-oms\/32077\/"},"wordCount":61,"commentCount":0,"articleSection":["En los medios"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/clam.org.br\/es\/en-los-medios\/mas-del-20-de-homosexuales-en-mexico-tienen-vih-oms\/32077\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/clam.org.br\/es\/en-los-medios\/mas-del-20-de-homosexuales-en-mexico-tienen-vih-oms\/32077\/","url":"https:\/\/clam.org.br\/es\/en-los-medios\/mas-del-20-de-homosexuales-en-mexico-tienen-vih-oms\/32077\/","name":"M\u00e1s del 20% de homosexuales en M\u00e9xico tienen VIH: OMS - CLAM - ES","isPartOf":{"@id":"https:\/\/clam.org.br\/es\/#website"},"datePublished":"2011-06-21T03:00:00+00:00","author":{"@id":"https:\/\/clam.org.br\/es\/#\/schema\/person\/fbd9a86032bf7479f94b0ded196f1010"},"breadcrumb":{"@id":"https:\/\/clam.org.br\/es\/en-los-medios\/mas-del-20-de-homosexuales-en-mexico-tienen-vih-oms\/32077\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/clam.org.br\/es\/en-los-medios\/mas-del-20-de-homosexuales-en-mexico-tienen-vih-oms\/32077\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/clam.org.br\/es\/en-los-medios\/mas-del-20-de-homosexuales-en-mexico-tienen-vih-oms\/32077\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/clam.org.br\/es\/"},{"@type":"ListItem","position":2,"name":"M\u00e1s del 20% de homosexuales en M\u00e9xico tienen VIH: OMS"}]},{"@type":"WebSite","@id":"https:\/\/clam.org.br\/es\/#website","url":"https:\/\/clam.org.br\/es\/","name":"CLAM - ES","description":"S\u00f3 mais um site CLAM - Centro Latino-Americano em Sexualidade e Direitos Humanos sites","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clam.org.br\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/clam.org.br\/es\/#\/schema\/person\/fbd9a86032bf7479f94b0ded196f1010","name":"fw2","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g","caption":"fw2"},"sameAs":["https:\/\/clam.org.br"],"url":"https:\/\/clam.org.br\/es\/author\/fw2\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/posts\/32077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/comments?post=32077"}],"version-history":[{"count":0,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/posts\/32077\/revisions"}],"wp:attachment":[{"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/media?parent=32077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/categories?post=32077"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/tags?post=32077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}