{"id":33272,"date":"2005-12-05T00:00:00","date_gmt":"2005-12-05T02:00:00","guid":{"rendered":"https:\/\/clam.fw2web.com.br\/es\/2005\/12\/05\/lancamento-do-livro-mortalidade-materna-e-direitos-humanos\/"},"modified":"2005-12-05T00:00:00","modified_gmt":"2005-12-05T02:00:00","slug":"lancamento-do-livro-mortalidade-materna-e-direitos-humanos","status":"publish","type":"post","link":"https:\/\/clam.org.br\/es\/agenda\/lancamento-do-livro-mortalidade-materna-e-direitos-humanos\/33272\/","title":{"rendered":"Lan\u00e7amento do livro &#8216;Mortalidade materna e Direitos Humanos&#8217;"},"content":{"rendered":"<p>O lan\u00e7amento do livro \u00abMortalidade materna e Direitos Humanos\u00bb, de Maria Beatriz Galli, Fl\u00e1via Piovesan e Val\u00e9ria Pandjiarjian, ocorrer\u00e1 no dia 7 de dezembro, \u00e0s 17h, no encerramento do \u00abIII Curso de Direitos Humanos das Mulheres\u00bb, promovido pelo Cepia &#8211; Cidadania, Estudo, Pesquisa, Informa\u00e7\u00e3o e A\u00e7\u00e3o, em parceria com a Defensoria P\u00fablica do Estado do Rio de Janeiro. O evento ocorrer\u00e1 na Defensoria P\u00fablica Geral do Estado do Rio de Janeiro, na rua Marechal C\u00e2mara, 314, Centro, Rio de Janeiro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O lan\u00e7amento do livro \u00abMortalidade materna e Direitos Humanos\u00bb, de Maria Beatriz Galli, Fl\u00e1via Piovesan e Val\u00e9ria Pandjiarjian, ocorrer\u00e1 no dia 7 de dezembro, \u00e0s 17h, no encerramento do \u00abIII Curso de Direitos Humanos das Mulheres\u00bb, promovido pelo Cepia &#8211; Cidadania, Estudo, Pesquisa, Informa\u00e7\u00e3o e A\u00e7\u00e3o, em parceria com a Defensoria P\u00fablica do Estado do Rio de Janeiro.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[28],"tags":[],"class_list":["post-33272","post","type-post","status-publish","format-standard","hentry","category-agenda"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lan\u00e7amento do livro &#039;Mortalidade materna e Direitos Humanos&#039; - CLAM - ES<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clam.org.br\/es\/agenda\/lancamento-do-livro-mortalidade-materna-e-direitos-humanos\/33272\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lan\u00e7amento do livro &#039;Mortalidade materna e Direitos Humanos&#039; - CLAM - ES\" \/>\n<meta property=\"og:description\" content=\"O lan\u00e7amento do livro &quot;Mortalidade materna e Direitos Humanos&quot;, de Maria Beatriz Galli, Fl\u00e1via Piovesan e Val\u00e9ria Pandjiarjian, ocorrer\u00e1 no dia 7 de dezembro, \u00e0s 17h, no encerramento do &quot;III Curso de Direitos Humanos das Mulheres&quot;, promovido pelo Cepia - Cidadania, Estudo, Pesquisa, Informa\u00e7\u00e3o e A\u00e7\u00e3o, em parceria com a Defensoria P\u00fablica do Estado do Rio de Janeiro.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clam.org.br\/es\/agenda\/lancamento-do-livro-mortalidade-materna-e-direitos-humanos\/33272\/\" \/>\n<meta property=\"og:site_name\" content=\"CLAM - ES\" \/>\n<meta property=\"article:published_time\" content=\"2005-12-05T02:00:00+00:00\" \/>\n<meta name=\"author\" content=\"fw2\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"fw2\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/agenda\\\/lancamento-do-livro-mortalidade-materna-e-direitos-humanos\\\/33272\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/agenda\\\/lancamento-do-livro-mortalidade-materna-e-direitos-humanos\\\/33272\\\/\"},\"author\":{\"name\":\"fw2\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#\\\/schema\\\/person\\\/fbd9a86032bf7479f94b0ded196f1010\"},\"headline\":\"Lan\u00e7amento do livro &#8216;Mortalidade materna e Direitos Humanos&#8217;\",\"datePublished\":\"2005-12-05T02:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/agenda\\\/lancamento-do-livro-mortalidade-materna-e-direitos-humanos\\\/33272\\\/\"},\"wordCount\":95,\"commentCount\":0,\"articleSection\":[\"Agenda\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/clam.org.br\\\/es\\\/agenda\\\/lancamento-do-livro-mortalidade-materna-e-direitos-humanos\\\/33272\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/agenda\\\/lancamento-do-livro-mortalidade-materna-e-direitos-humanos\\\/33272\\\/\",\"url\":\"https:\\\/\\\/clam.org.br\\\/es\\\/agenda\\\/lancamento-do-livro-mortalidade-materna-e-direitos-humanos\\\/33272\\\/\",\"name\":\"Lan\u00e7amento do livro 'Mortalidade materna e Direitos Humanos' - CLAM - ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#website\"},\"datePublished\":\"2005-12-05T02:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#\\\/schema\\\/person\\\/fbd9a86032bf7479f94b0ded196f1010\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/agenda\\\/lancamento-do-livro-mortalidade-materna-e-direitos-humanos\\\/33272\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/clam.org.br\\\/es\\\/agenda\\\/lancamento-do-livro-mortalidade-materna-e-direitos-humanos\\\/33272\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/agenda\\\/lancamento-do-livro-mortalidade-materna-e-direitos-humanos\\\/33272\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/clam.org.br\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lan\u00e7amento do livro &#8216;Mortalidade materna e Direitos Humanos&#8217;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/clam.org.br\\\/es\\\/\",\"name\":\"CLAM - ES\",\"description\":\"S\u00f3 mais um site CLAM - Centro Latino-Americano em Sexualidade e Direitos Humanos sites\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/clam.org.br\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#\\\/schema\\\/person\\\/fbd9a86032bf7479f94b0ded196f1010\",\"name\":\"fw2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g\",\"caption\":\"fw2\"},\"sameAs\":[\"https:\\\/\\\/clam.org.br\"],\"url\":\"https:\\\/\\\/clam.org.br\\\/es\\\/author\\\/fw2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lan\u00e7amento do livro 'Mortalidade materna e Direitos Humanos' - CLAM - ES","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clam.org.br\/es\/agenda\/lancamento-do-livro-mortalidade-materna-e-direitos-humanos\/33272\/","og_locale":"es_ES","og_type":"article","og_title":"Lan\u00e7amento do livro 'Mortalidade materna e Direitos Humanos' - CLAM - ES","og_description":"O lan\u00e7amento do livro \"Mortalidade materna e Direitos Humanos\", de Maria Beatriz Galli, Fl\u00e1via Piovesan e Val\u00e9ria Pandjiarjian, ocorrer\u00e1 no dia 7 de dezembro, \u00e0s 17h, no encerramento do \"III Curso de Direitos Humanos das Mulheres\", promovido pelo Cepia - Cidadania, Estudo, Pesquisa, Informa\u00e7\u00e3o e A\u00e7\u00e3o, em parceria com a Defensoria P\u00fablica do Estado do Rio de Janeiro.","og_url":"https:\/\/clam.org.br\/es\/agenda\/lancamento-do-livro-mortalidade-materna-e-direitos-humanos\/33272\/","og_site_name":"CLAM - ES","article_published_time":"2005-12-05T02:00:00+00:00","author":"fw2","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"fw2"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/clam.org.br\/es\/agenda\/lancamento-do-livro-mortalidade-materna-e-direitos-humanos\/33272\/#article","isPartOf":{"@id":"https:\/\/clam.org.br\/es\/agenda\/lancamento-do-livro-mortalidade-materna-e-direitos-humanos\/33272\/"},"author":{"name":"fw2","@id":"https:\/\/clam.org.br\/es\/#\/schema\/person\/fbd9a86032bf7479f94b0ded196f1010"},"headline":"Lan\u00e7amento do livro &#8216;Mortalidade materna e Direitos Humanos&#8217;","datePublished":"2005-12-05T02:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/clam.org.br\/es\/agenda\/lancamento-do-livro-mortalidade-materna-e-direitos-humanos\/33272\/"},"wordCount":95,"commentCount":0,"articleSection":["Agenda"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/clam.org.br\/es\/agenda\/lancamento-do-livro-mortalidade-materna-e-direitos-humanos\/33272\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/clam.org.br\/es\/agenda\/lancamento-do-livro-mortalidade-materna-e-direitos-humanos\/33272\/","url":"https:\/\/clam.org.br\/es\/agenda\/lancamento-do-livro-mortalidade-materna-e-direitos-humanos\/33272\/","name":"Lan\u00e7amento do livro 'Mortalidade materna e Direitos Humanos' - CLAM - ES","isPartOf":{"@id":"https:\/\/clam.org.br\/es\/#website"},"datePublished":"2005-12-05T02:00:00+00:00","author":{"@id":"https:\/\/clam.org.br\/es\/#\/schema\/person\/fbd9a86032bf7479f94b0ded196f1010"},"breadcrumb":{"@id":"https:\/\/clam.org.br\/es\/agenda\/lancamento-do-livro-mortalidade-materna-e-direitos-humanos\/33272\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/clam.org.br\/es\/agenda\/lancamento-do-livro-mortalidade-materna-e-direitos-humanos\/33272\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/clam.org.br\/es\/agenda\/lancamento-do-livro-mortalidade-materna-e-direitos-humanos\/33272\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/clam.org.br\/es\/"},{"@type":"ListItem","position":2,"name":"Lan\u00e7amento do livro &#8216;Mortalidade materna e Direitos Humanos&#8217;"}]},{"@type":"WebSite","@id":"https:\/\/clam.org.br\/es\/#website","url":"https:\/\/clam.org.br\/es\/","name":"CLAM - ES","description":"S\u00f3 mais um site CLAM - Centro Latino-Americano em Sexualidade e Direitos Humanos sites","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clam.org.br\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/clam.org.br\/es\/#\/schema\/person\/fbd9a86032bf7479f94b0ded196f1010","name":"fw2","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g","caption":"fw2"},"sameAs":["https:\/\/clam.org.br"],"url":"https:\/\/clam.org.br\/es\/author\/fw2\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/posts\/33272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/comments?post=33272"}],"version-history":[{"count":0,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/posts\/33272\/revisions"}],"wp:attachment":[{"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/media?parent=33272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/categories?post=33272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/tags?post=33272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}