{"id":34349,"date":"2012-06-25T00:00:00","date_gmt":"2012-06-25T03:00:00","guid":{"rendered":"https:\/\/clam.fw2web.com.br\/es\/2012\/06\/25\/foro-sobre-ley-antidiscriminacion\/"},"modified":"2012-06-25T00:00:00","modified_gmt":"2012-06-25T03:00:00","slug":"foro-sobre-ley-antidiscriminacion","status":"publish","type":"post","link":"https:\/\/clam.org.br\/es\/agenda\/foro-sobre-ley-antidiscriminacion\/34349\/","title":{"rendered":"Foro sobre Ley Antidiscriminaci\u00f3n"},"content":{"rendered":"<p>El pr&oacute;ximo 28 de junio, de 8:30 am a 12:30 pm, se llevar&aacute; a cabo el Foro <b>#NoDiscrimino: Pongamos en Marcha la Ley Anti-Discriminaci&oacute;n<\/b> en el que se analizar&aacute; el alcance de la Ley 1482 de 2011 y la necesidad de generar procesos de sensibilizaci&oacute;n institucional para su efectiva aplicaci&oacute;n.<\/p>\n<p>El foro contar&aacute; con la participaci&oacute;n de congresistas que impulsaron la Ley, reconocidos juristas nacionales y como invitada internacional participar&aacute; la Dra. Donna Payne, Directora de Diversidad de Human Rights Campaign, una de las organizaciones de derechos civiles m&aacute;s importantes de los Estados Unidos.<\/p>\n<p>El evento tendr&aacute; lugar en el Aula M&aacute;xima de la Universidad del Rosario (Calle 14 # 6 &#8211; 25, Bogot&aacute;).<\/p>\n<p><b>Agenda<\/b><\/p>\n<p>Modera: Dr. Francisco Herrero &ndash; Director para Colombia del National Democratic Institute<\/p>\n<p><b>Elementos para la Implementaci&oacute;n de la Ley 1482 de 2011<\/b><\/p>\n<p>Dr. Luis Eduardo Montealegre &ndash; Fiscal General de la Naci&oacute;n<br \/> Dr. Carlos Baena &ndash; Senador de la Rep&uacute;blica<br \/> Dr. Alfonso Prada &ndash; Representante a la C&aacute;mara<\/p>\n<p><b>Lecciones aprendidas en Lucha por los Derechos Civiles en los EEUU<\/b><\/p>\n<p>Dra. Donna Payne &ndash; Directora de Diversidad, Human Rights Campaign<\/p>\n<p><b>Presentaci&oacute;n de Casos de Discriminaci&oacute;n<\/b><\/p>\n<p>Dr. Felipe Montoya &ndash; Demanda penal contra &Aacute;lvaro Gonz&aacute;les, presidente de la Divisi&oacute;n Aficionada de Futbol, por declaraciones homof&oacute;bicas. <br \/> Heiler Ledezma &ndash; Demanda contra la Universidad Distrital por discriminaci&oacute;n racial<br \/> Jineth Bedoya &ndash; Denuncia contra el Estado colombiano por el secuestro, la tortura y la violencia sexual cometidos contra ella.<\/p>\n<p><b>Herramientas para Combatir la Discriminaci&oacute;n<\/b><\/p>\n<p>Dr. Rodrigo Uprimny &ndash; Magistrado auxiliar y director del Centro de Investigaci&oacute;n DeJusticia. <br \/> Dr. Juan Carlos Lancheros &ndash; Director de la Fundaci&oacute;n Derecho Justo<\/p>\n<p><b>Invitan: <\/b><\/p>\n<p>La Asociaci&oacute;n de Mujeres Anna Perenna<br \/> La Corporaci&oacute;n SISMA Mujer<br \/> La Red Nacional de Mujeres<br \/> El Movimiento Nacional Afrocolombiano Cimarr&oacute;n<br \/> La Corporaci&oacute;n Red Somos<br \/> Trans-Ser<br \/> La Fundaci&oacute;n Afroamigos<br \/> El Centro de Estudios para la Democracia Colombia Siglo XXI<br \/> La Fundaci&oacute;n ACUA<br \/> El Grupo de investigaci&oacute;n IDCAR&Aacute;N &#8211; FCH &#8211; CES de la Universidad Nacional <br \/> El Instituto Nacional Dem&oacute;crata &ndash;NDI Colombia&ndash;<\/p>\n<p><strong>La entrada al evento es libre.<\/strong><\/p>\n<p><strong>Para inscribirse, <\/strong><a href=\"https:\/\/docs.google.com\/spreadsheet\/viewform?formkey=dHY3SVFsdUF5NTNJRkg3eGhmYVd4Q0E6MA\"><strong>haga clic aqu&iacute;<\/strong><\/a>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pr\u00f3ximo 28 de junio, de 8:30 am a 12:30 pm, se llevar\u00e1 a cabo el Foro #NoDiscrimino: Pongamos en Marcha la Ley Anti-Discriminaci\u00f3n en el que se analizar\u00e1 el alcance de la Ley 1482 de 2011 y la necesidad de generar procesos de sensibilizaci\u00f3n institucional para su efectiva aplicaci\u00f3n.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[28],"tags":[],"class_list":["post-34349","post","type-post","status-publish","format-standard","hentry","category-agenda"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Foro sobre Ley Antidiscriminaci\u00f3n - CLAM - ES<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clam.org.br\/es\/agenda\/foro-sobre-ley-antidiscriminacion\/34349\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Foro sobre Ley Antidiscriminaci\u00f3n - CLAM - ES\" \/>\n<meta property=\"og:description\" content=\"El pr\u00f3ximo 28 de junio, de 8:30 am a 12:30 pm, se llevar\u00e1 a cabo el Foro #NoDiscrimino: Pongamos en Marcha la Ley Anti-Discriminaci\u00f3n en el que se analizar\u00e1 el alcance de la Ley 1482 de 2011 y la necesidad de generar procesos de sensibilizaci\u00f3n institucional para su efectiva aplicaci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clam.org.br\/es\/agenda\/foro-sobre-ley-antidiscriminacion\/34349\/\" \/>\n<meta property=\"og:site_name\" content=\"CLAM - ES\" \/>\n<meta property=\"article:published_time\" content=\"2012-06-25T03:00:00+00:00\" \/>\n<meta name=\"author\" content=\"fw2\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"fw2\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/agenda\\\/foro-sobre-ley-antidiscriminacion\\\/34349\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/agenda\\\/foro-sobre-ley-antidiscriminacion\\\/34349\\\/\"},\"author\":{\"name\":\"fw2\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#\\\/schema\\\/person\\\/fbd9a86032bf7479f94b0ded196f1010\"},\"headline\":\"Foro sobre Ley Antidiscriminaci\u00f3n\",\"datePublished\":\"2012-06-25T03:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/agenda\\\/foro-sobre-ley-antidiscriminacion\\\/34349\\\/\"},\"wordCount\":403,\"commentCount\":0,\"articleSection\":[\"Agenda\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/clam.org.br\\\/es\\\/agenda\\\/foro-sobre-ley-antidiscriminacion\\\/34349\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/agenda\\\/foro-sobre-ley-antidiscriminacion\\\/34349\\\/\",\"url\":\"https:\\\/\\\/clam.org.br\\\/es\\\/agenda\\\/foro-sobre-ley-antidiscriminacion\\\/34349\\\/\",\"name\":\"Foro sobre Ley Antidiscriminaci\u00f3n - CLAM - ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#website\"},\"datePublished\":\"2012-06-25T03:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#\\\/schema\\\/person\\\/fbd9a86032bf7479f94b0ded196f1010\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/agenda\\\/foro-sobre-ley-antidiscriminacion\\\/34349\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/clam.org.br\\\/es\\\/agenda\\\/foro-sobre-ley-antidiscriminacion\\\/34349\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/agenda\\\/foro-sobre-ley-antidiscriminacion\\\/34349\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/clam.org.br\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Foro sobre Ley Antidiscriminaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/clam.org.br\\\/es\\\/\",\"name\":\"CLAM - ES\",\"description\":\"S\u00f3 mais um site CLAM - Centro Latino-Americano em Sexualidade e Direitos Humanos sites\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/clam.org.br\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#\\\/schema\\\/person\\\/fbd9a86032bf7479f94b0ded196f1010\",\"name\":\"fw2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g\",\"caption\":\"fw2\"},\"sameAs\":[\"https:\\\/\\\/clam.org.br\"],\"url\":\"https:\\\/\\\/clam.org.br\\\/es\\\/author\\\/fw2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Foro sobre Ley Antidiscriminaci\u00f3n - CLAM - ES","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clam.org.br\/es\/agenda\/foro-sobre-ley-antidiscriminacion\/34349\/","og_locale":"es_ES","og_type":"article","og_title":"Foro sobre Ley Antidiscriminaci\u00f3n - CLAM - ES","og_description":"El pr\u00f3ximo 28 de junio, de 8:30 am a 12:30 pm, se llevar\u00e1 a cabo el Foro #NoDiscrimino: Pongamos en Marcha la Ley Anti-Discriminaci\u00f3n en el que se analizar\u00e1 el alcance de la Ley 1482 de 2011 y la necesidad de generar procesos de sensibilizaci\u00f3n institucional para su efectiva aplicaci\u00f3n.","og_url":"https:\/\/clam.org.br\/es\/agenda\/foro-sobre-ley-antidiscriminacion\/34349\/","og_site_name":"CLAM - ES","article_published_time":"2012-06-25T03:00:00+00:00","author":"fw2","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"fw2","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/clam.org.br\/es\/agenda\/foro-sobre-ley-antidiscriminacion\/34349\/#article","isPartOf":{"@id":"https:\/\/clam.org.br\/es\/agenda\/foro-sobre-ley-antidiscriminacion\/34349\/"},"author":{"name":"fw2","@id":"https:\/\/clam.org.br\/es\/#\/schema\/person\/fbd9a86032bf7479f94b0ded196f1010"},"headline":"Foro sobre Ley Antidiscriminaci\u00f3n","datePublished":"2012-06-25T03:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/clam.org.br\/es\/agenda\/foro-sobre-ley-antidiscriminacion\/34349\/"},"wordCount":403,"commentCount":0,"articleSection":["Agenda"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/clam.org.br\/es\/agenda\/foro-sobre-ley-antidiscriminacion\/34349\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/clam.org.br\/es\/agenda\/foro-sobre-ley-antidiscriminacion\/34349\/","url":"https:\/\/clam.org.br\/es\/agenda\/foro-sobre-ley-antidiscriminacion\/34349\/","name":"Foro sobre Ley Antidiscriminaci\u00f3n - CLAM - ES","isPartOf":{"@id":"https:\/\/clam.org.br\/es\/#website"},"datePublished":"2012-06-25T03:00:00+00:00","author":{"@id":"https:\/\/clam.org.br\/es\/#\/schema\/person\/fbd9a86032bf7479f94b0ded196f1010"},"breadcrumb":{"@id":"https:\/\/clam.org.br\/es\/agenda\/foro-sobre-ley-antidiscriminacion\/34349\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/clam.org.br\/es\/agenda\/foro-sobre-ley-antidiscriminacion\/34349\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/clam.org.br\/es\/agenda\/foro-sobre-ley-antidiscriminacion\/34349\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/clam.org.br\/es\/"},{"@type":"ListItem","position":2,"name":"Foro sobre Ley Antidiscriminaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/clam.org.br\/es\/#website","url":"https:\/\/clam.org.br\/es\/","name":"CLAM - ES","description":"S\u00f3 mais um site CLAM - Centro Latino-Americano em Sexualidade e Direitos Humanos sites","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clam.org.br\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/clam.org.br\/es\/#\/schema\/person\/fbd9a86032bf7479f94b0ded196f1010","name":"fw2","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g","caption":"fw2"},"sameAs":["https:\/\/clam.org.br"],"url":"https:\/\/clam.org.br\/es\/author\/fw2\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/posts\/34349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/comments?post=34349"}],"version-history":[{"count":0,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/posts\/34349\/revisions"}],"wp:attachment":[{"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/media?parent=34349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/categories?post=34349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/tags?post=34349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}