{"id":739,"date":"2012-04-18T00:00:00","date_gmt":"2012-04-18T03:00:00","guid":{"rendered":"https:\/\/clam.org.br\/es\/2012\/04\/18\/el-legado-de-gilberto\/"},"modified":"2012-04-18T00:00:00","modified_gmt":"2012-04-18T03:00:00","slug":"el-legado-de-gilberto","status":"publish","type":"post","link":"https:\/\/clam.org.br\/es\/noticias-clam\/el-legado-de-gilberto\/739\/","title":{"rendered":"El legado de Gilberto"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" hspace=\"5\" vspace=\"5\" align=\"left\" width=\"200\" height=\"267\" alt=\"\" src=\"\/uploads\/imagem\/foto_Gilberto.JPG\" \/>O trabalho de Gilberto Velho (1945-2012), <a target=\"_blank\" href=\"http:\/\/www.youtube.com\/watch?feature=player_embedded&amp;v=aU_5Y7icrmA#!\" rel=\"noopener\">conforme descrito por ele pr&oacute;prio<\/a> durante a 32&ordf; Reuni&atilde;o Anual da Anpocs, em 2008, foi sobretudo um trabalho de interlocutor, de estimular pesquisas, de orientar teses e disserta&ccedil;&otilde;es, e de organizar reuni&otilde;es atrav&eacute;s das sociedades e inst&acirc;ncias cient&iacute;ficas que presidiu, como a ABA e a Anpocs.<br \/> &nbsp;<\/p>\n<p>Pioneiro na linha da antropologia urbana no Brasil, Gilberto dispensava aten&ccedil;&atilde;o para o que n&atilde;o era convencional, teve contato estreito com a problem&aacute;tica do desvio e da transgress&atilde;o, especialmente em rela&ccedil;&atilde;o ao uso de drogas. Aberto intelectualmente, tinha um descortino a temas sens&iacute;veis, falava da complexidade do mundo social. Seu interesse pela literatura e fasc&iacute;nio pela antiguidade ampliou o horizonte de sensibilidade aos variados temas de pesquisa que ele orientava.<br \/> &nbsp;<\/p>\n<p><i>&ldquo;Meu interesse em hist&oacute;ria e literatura fez com que, quando eu me aproximei da antropologia, j&aacute; tivesse a atitude de observar participando&rdquo;<\/i>, ele lembrou em certa ocasi&atilde;o.<br \/> &nbsp;<\/p>\n<p>Gilberto Velho inaugurou o campo da antropologia urbana no pa&iacute;s, publicando in&uacute;meros livros e artigos sobre assuntos diversos, desde a Utopia Urbana (1973) &ndash; no qual escreveu sobre a experi&ecirc;ncia social de morar num pr&eacute;dio de conjugados em Copacabana &ndash; a temas candentes, como a viol&ecirc;ncia urbana e o significado social e pol&iacute;tico das drogas. Elaborou, a partir de di&aacute;logo&nbsp;fundado em Georg Simmel e Louis Dumont, modos inovadores de pensar o fen&ocirc;meno do individualismo. Centrou-se no estudo de conceitos como &ldquo;camadas m&eacute;dias&rdquo; e na problematiza&ccedil;&atilde;o do &ldquo;desvio e diverg&ecirc;ncia&rdquo;.<\/p>\n<p> Sempre aberto a temas para os quais muitas vezes os cientistas sociais ainda n&atilde;o davam aten&ccedil;&atilde;o, como a legaliza&ccedil;&atilde;o das drogas, a sexualidade, a vida urbana e a seguran&ccedil;a p&uacute;blica, influenciou o pensamento brasileiro. Teve papel importante na institucionaliza&ccedil;&atilde;o das Ci&ecirc;ncias Sociais no Brasil e sua internacionaliza&ccedil;&atilde;o, e foi pe&ccedil;a-chave na consolida&ccedil;&atilde;o do programa de p&oacute;s-gradua&ccedil;&atilde;o do Museu Nacional.<\/p>\n<p> Instigava-o a discuss&atilde;o de indiv&iacute;duo e sociedade e a quest&atilde;o das trajet&oacute;rias individuais, das op&ccedil;&otilde;es, das escolhas, e atribu&iacute;a isto a seu contato com a literatura existencialista de Jean-Paul Sartre. Por esta generosidade de seu olhar sobre variados temas, incluindo a sexualidade, orientou uma das primeiras teses sobre homossexualidade no pa&iacute;s &ndash; &ldquo;O homossexual visto por entendidos&rdquo;, de Carmem Dora Guimar&atilde;es, em 1977 &ndash; hoje publicada na Cole&ccedil;&atilde;o Sexualidade, G&ecirc;nero e Sociedade (CLAM\/Garamond Universit&aacute;ria). Al&eacute;m disso, orientou v&aacute;rios outros trabalhos fundamentais para a consolida&ccedil;&atilde;o deste campo de pesquisa no Brasil, como &ldquo;Dois &eacute; par: conjugalidade, g&ecirc;nero e identidade&rdquo;, tese de doutorado defendida por Maria Luiza Heilborn em 1992.<\/p>\n<p> Ao longo de sua carreira, foram 61 disserta&ccedil;&otilde;es de mestrado e 35 teses de doutorado, o que representa toda uma gera&ccedil;&atilde;o de antrop&oacute;logos que, por sua vez, formaram e continuam a formar novos pesquisadores em diversos campos nas universidades brasileiras. Introduziu inova&ccedil;&otilde;es intelectuais importantes no Brasil e orientou nomes como Luiz Fernando Dias Duarte &ndash; &ldquo;Da vida nervosa: pessoa e modernidade entre as classes trabalhadoras&rdquo; (1985) &ndash;, Karina Kuschnir &ndash; &ldquo;Pol&iacute;tica e sociabilidade: um estudo de antropologia social&rdquo; (1998) &ndash;, Myriam Lins de Barros &ndash; &ldquo;Testemunho de vida: um estudo antropol&oacute;gico de mulheres na velhice&rdquo; (1980) &ndash;, Jane Russo &#8211; &quot;O corpo contra a palavra: as terapias corporais no campo psicol&oacute;gico dos anos 80&quot; (1991) -,&nbsp;entre outros.<\/p>\n<p> <a target=\"_blank\" href=\"http:\/\/lau-ufrj.blogspot.com.br\/2012\/04\/gilberto-velho-1945-2012.html\" rel=\"noopener\">Em nota pessoal<\/a>, Karina Kuschnir ressaltou a obsessiva disciplina do antrop&oacute;logo para orientar. <em>&quot;Cobrava, reclamava e brigava &#8211; muito. Mas tentava compensar essa rigidez com um imenso afeto e vontade de nos ver crescer&quot;.<\/em> &Agrave; antrop&oacute;loga colombiana Maria Elvira Diaz-Benitez, sua orientanda na tese&nbsp; &quot;Nas redes do sexo: bastidores e cen&aacute;rios do porn&ocirc; brasileiro&quot; (2009), ele aconselhava, de modo paternal: <em>&quot;Tenha cuidado com os limites do bizarro, n&atilde;o se exponha demais&quot;<\/em>. Quando prop&ocirc;s o tema de sua disserta&ccedil;&atilde;o de mestrado &quot;O baile funk: festas e estilos de vida metropolitana&quot; (1987),&nbsp;Hermano Vianna convidou o orientador a acompanh&aacute;-lo&nbsp;a um baile funk no sub&uacute;rbio carioca. Gilberto o acompanhou. Colega de doc&ecirc;ncia no Museu Nacional, Adrianna Vianna destaca que o&nbsp;bom humor e o olhar arguto eram suas caracter&iacute;sticas marcantes.<\/p>\n<p>No plano da pol&iacute;tica institucional, Gilberto Velho ocupou posi&ccedil;&otilde;es importantes: foi presidente da Anpocs e da ABA, e, em 2000, tornou-se o primeiro cientista social a ser incorporado &agrave; Academia Brasileira de Ci&ecirc;ncias (ABC), at&eacute; ent&atilde;o restrita a pesquisadores e cientistas do &acirc;mbito das ci&ecirc;ncias exatas e naturais. Foi condecorado com a Ordem Nacional do M&eacute;rito Cient&iacute;fico, com o grau de comendador, em 1995, e com o grau Gr&atilde;-Cruz, em 2000, da Presid&ecirc;ncia da Rep&uacute;blica. Em 1999, tamb&eacute;m foi condecorado comendador da Ordem do Rio Branco, do Minist&eacute;rio das Rela&ccedil;&otilde;es Exteriores.<\/p>\n<p> Publicou 113 artigos em peri&oacute;dicos e 28 livros, v&aacute;rios dos quais colet&acirc;neas produzidas com alunos e ex-alunos, uma delas o famoso <i>Desvio e Diverg&ecirc;ncia: uma cr&iacute;tica da patologia social<\/i> que, ao ser lan&ccedil;ado exitosamente para os padr&otilde;es da &eacute;poca, fez com que um intelectual dissesse: &ldquo;N&atilde;o tem sentido um antrop&oacute;logo estudar <i>puta<\/i> e <i>viado<\/i>. Antrop&oacute;logo tem que estudar &iacute;ndio&rdquo;. Anos depois, ao relembrar o fato, o antrop&oacute;logo observou: &ldquo;O fato &eacute; que as pessoas t&ecirc;m o direito a opini&otilde;es diferentes. O que n&atilde;o pode se aceitar &eacute; que tentem barrar o caminho de outras&rdquo;.<\/p>\n<p> <a target=\"_blank\" href=\"http:\/\/www.youtube.com\/watch?feature=player_embedded&amp;v=aU_5Y7icrmA#!\" rel=\"noopener\">Assista v&iacute;deo da conversa com Gilberto Velho realizada no 32&ordm; Encontro Anual da Anpocs &#8211; 2008 <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abNo es que quiera negar la importancia de grandes fuerzas sociales, la presi\u00f3n social o la cultura, s\u00f3lo que valoro una noci\u00f3n de libertad, la cuesti\u00f3n de las trayectorias individuales, de las opciones y elecciones\u00bb. Gilberto Velho (1945-2012). Ilustraci\u00f3n de Maria Luiza Heilborn, amiga y ex-orientada. (Texto en portugu\u00e9s)<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-739","post","type-post","status-publish","format-standard","hentry","category-noticias-clam"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El legado de Gilberto - CLAM - ES<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clam.org.br\/es\/noticias-clam\/el-legado-de-gilberto\/739\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El legado de Gilberto - CLAM - ES\" \/>\n<meta property=\"og:description\" content=\"&quot;No es que quiera negar la importancia de grandes fuerzas sociales, la presi\u00f3n social o la cultura, s\u00f3lo que valoro una noci\u00f3n de libertad, la cuesti\u00f3n de las trayectorias individuales, de las opciones y elecciones&quot;. Gilberto Velho (1945-2012). Ilustraci\u00f3n de Maria Luiza Heilborn, amiga y ex-orientada. (Texto en portugu\u00e9s)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clam.org.br\/es\/noticias-clam\/el-legado-de-gilberto\/739\/\" \/>\n<meta property=\"og:site_name\" content=\"CLAM - ES\" \/>\n<meta property=\"article:published_time\" content=\"2012-04-18T03:00:00+00:00\" \/>\n<meta name=\"author\" content=\"fw2\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"fw2\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/noticias-clam\\\/el-legado-de-gilberto\\\/739\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/noticias-clam\\\/el-legado-de-gilberto\\\/739\\\/\"},\"author\":{\"name\":\"fw2\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#\\\/schema\\\/person\\\/fbd9a86032bf7479f94b0ded196f1010\"},\"headline\":\"El legado de Gilberto\",\"datePublished\":\"2012-04-18T03:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/noticias-clam\\\/el-legado-de-gilberto\\\/739\\\/\"},\"wordCount\":1100,\"commentCount\":0,\"articleSection\":[\"noticias CLAM\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/clam.org.br\\\/es\\\/noticias-clam\\\/el-legado-de-gilberto\\\/739\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/noticias-clam\\\/el-legado-de-gilberto\\\/739\\\/\",\"url\":\"https:\\\/\\\/clam.org.br\\\/es\\\/noticias-clam\\\/el-legado-de-gilberto\\\/739\\\/\",\"name\":\"El legado de Gilberto - CLAM - ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#website\"},\"datePublished\":\"2012-04-18T03:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#\\\/schema\\\/person\\\/fbd9a86032bf7479f94b0ded196f1010\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/noticias-clam\\\/el-legado-de-gilberto\\\/739\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/clam.org.br\\\/es\\\/noticias-clam\\\/el-legado-de-gilberto\\\/739\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/noticias-clam\\\/el-legado-de-gilberto\\\/739\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/clam.org.br\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El legado de Gilberto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/clam.org.br\\\/es\\\/\",\"name\":\"CLAM - ES\",\"description\":\"S\u00f3 mais um site CLAM - Centro Latino-Americano em Sexualidade e Direitos Humanos sites\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/clam.org.br\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/clam.org.br\\\/es\\\/#\\\/schema\\\/person\\\/fbd9a86032bf7479f94b0ded196f1010\",\"name\":\"fw2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g\",\"caption\":\"fw2\"},\"sameAs\":[\"https:\\\/\\\/clam.org.br\"],\"url\":\"https:\\\/\\\/clam.org.br\\\/es\\\/author\\\/fw2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El legado de Gilberto - CLAM - ES","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clam.org.br\/es\/noticias-clam\/el-legado-de-gilberto\/739\/","og_locale":"es_ES","og_type":"article","og_title":"El legado de Gilberto - CLAM - ES","og_description":"\"No es que quiera negar la importancia de grandes fuerzas sociales, la presi\u00f3n social o la cultura, s\u00f3lo que valoro una noci\u00f3n de libertad, la cuesti\u00f3n de las trayectorias individuales, de las opciones y elecciones\". Gilberto Velho (1945-2012). Ilustraci\u00f3n de Maria Luiza Heilborn, amiga y ex-orientada. (Texto en portugu\u00e9s)","og_url":"https:\/\/clam.org.br\/es\/noticias-clam\/el-legado-de-gilberto\/739\/","og_site_name":"CLAM - ES","article_published_time":"2012-04-18T03:00:00+00:00","author":"fw2","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"fw2","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/clam.org.br\/es\/noticias-clam\/el-legado-de-gilberto\/739\/#article","isPartOf":{"@id":"https:\/\/clam.org.br\/es\/noticias-clam\/el-legado-de-gilberto\/739\/"},"author":{"name":"fw2","@id":"https:\/\/clam.org.br\/es\/#\/schema\/person\/fbd9a86032bf7479f94b0ded196f1010"},"headline":"El legado de Gilberto","datePublished":"2012-04-18T03:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/clam.org.br\/es\/noticias-clam\/el-legado-de-gilberto\/739\/"},"wordCount":1100,"commentCount":0,"articleSection":["noticias CLAM"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/clam.org.br\/es\/noticias-clam\/el-legado-de-gilberto\/739\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/clam.org.br\/es\/noticias-clam\/el-legado-de-gilberto\/739\/","url":"https:\/\/clam.org.br\/es\/noticias-clam\/el-legado-de-gilberto\/739\/","name":"El legado de Gilberto - CLAM - ES","isPartOf":{"@id":"https:\/\/clam.org.br\/es\/#website"},"datePublished":"2012-04-18T03:00:00+00:00","author":{"@id":"https:\/\/clam.org.br\/es\/#\/schema\/person\/fbd9a86032bf7479f94b0ded196f1010"},"breadcrumb":{"@id":"https:\/\/clam.org.br\/es\/noticias-clam\/el-legado-de-gilberto\/739\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/clam.org.br\/es\/noticias-clam\/el-legado-de-gilberto\/739\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/clam.org.br\/es\/noticias-clam\/el-legado-de-gilberto\/739\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/clam.org.br\/es\/"},{"@type":"ListItem","position":2,"name":"El legado de Gilberto"}]},{"@type":"WebSite","@id":"https:\/\/clam.org.br\/es\/#website","url":"https:\/\/clam.org.br\/es\/","name":"CLAM - ES","description":"S\u00f3 mais um site CLAM - Centro Latino-Americano em Sexualidade e Direitos Humanos sites","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clam.org.br\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/clam.org.br\/es\/#\/schema\/person\/fbd9a86032bf7479f94b0ded196f1010","name":"fw2","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/54ecf5cded291fb93319a89ac5574f1a59c63c407a36d7ccb710f487e3467ea0?s=96&d=mm&r=g","caption":"fw2"},"sameAs":["https:\/\/clam.org.br"],"url":"https:\/\/clam.org.br\/es\/author\/fw2\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/posts\/739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/comments?post=739"}],"version-history":[{"count":0,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/posts\/739\/revisions"}],"wp:attachment":[{"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/media?parent=739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/categories?post=739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clam.org.br\/es\/wp-json\/wp\/v2\/tags?post=739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}